{"id":32140,"date":"2026-05-13T09:28:11","date_gmt":"2026-05-13T13:28:11","guid":{"rendered":"https:\/\/www.americanonewspaper.com\/es\/?p=32140"},"modified":"2026-05-13T09:28:17","modified_gmt":"2026-05-13T13:28:17","slug":"manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar","status":"publish","type":"post","link":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/","title":{"rendered":"Manej\u00f3 un autob\u00fas escolar durante 21 a\u00f1os. Ahora perdi\u00f3 su autorizaci\u00f3n legal para trabajar"},"content":{"rendered":"\n<p><strong>Inmigrante hondure\u00f1a perdi\u00f3 su derecho a trabajar<\/strong><\/p>\n\n\n\n<p>Por Hannan Adely, NorthJersey.com<\/p>\n\n\n\n<p class=\"dropcapp3\">Durante 21 a\u00f1os, Maribel Urbina manej\u00f3 un autob\u00fas escolar de 54 pasajeros.<\/p>\n\n\n\n<p>Recorri\u00f3 las calles de la ciudad de Nueva York y las carreteras suburbanas. Transportaba a los estudiantes desde y hacia la escuela Dwight-Englewood. Los llevaba a excursiones escolares, al teatro y al zool\u00f3gico.<\/p>\n\n\n\n<p>Amaba su trabajo, que le brindaba seguridad en su vida en Englewood, donde cri\u00f3 a sus cuatro hijos en su casa de dos habitaciones.<\/p>\n\n\n\n<p>Sin embargo, el oto\u00f1o pasado, perdi\u00f3 su estatus migratorio y con ello su capacidad para trabajar legalmente en Estados Unidos.<\/p>\n\n\n\n<p>&#8220;Cada d\u00eda me alegraba saber que ten\u00eda trabajo, que pod\u00eda conducir&#8221;, dijo Urbina entre l\u00e1grimas. &#8220;Ahora me despierto y veo que no puedo hacerlo. Esto me entristece mucho&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/ggllawyers.com\/es\/new-jersey-personal-injury-and-workers-compensation-lawyer\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img fetchpriority=\"high\" decoding=\"async\" width=\"560\" height=\"269\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/GGlSpanish-1.jpg\" alt=\"Abogados de Accidentes\" class=\"wp-image-32092\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/GGlSpanish-1.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/GGlSpanish-1-300x144.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/GGlSpanish-1-150x72.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><figcaption class=\"wp-element-caption\">Abogados de Accidentes<\/figcaption><\/figure>\n\n\n\n<p>Urbina se encuentra entre un n\u00famero creciente de inmigrantes que han perdido la autorizaci\u00f3n legal para trabajar a medida que la administraci\u00f3n Trump desmantela o reduce los programas de inmigraci\u00f3n y endurece las normas de autorizaci\u00f3n laboral.<\/p>\n\n\n\n<p>Estos cambios, que incluyen permisos de trabajo de menor duraci\u00f3n y nuevas restricciones de elegibilidad, han truncado abruptamente los medios de subsistencia, empujando a las familias hacia una crisis financiera. A medida que se intensifica la aplicaci\u00f3n de la ley y las pol\u00edticas cambian constantemente, los empleadores se muestran cada vez m\u00e1s reacios a contratar o mantener a trabajadores cuyo estatus migratorio podr\u00eda verse afectado.<\/p>\n\n\n\n<p>Los defensores de los inmigrantes afirman que estas pol\u00edticas socavan las <a href=\"https:\/\/uscode.house.gov\/view.xhtml?path=\/prelim@title8\/chapter14&amp;edition=prelim#:~:text=%C2%A71601.%20Statements%20of%20national,to%20the%20United%20States\">directrices federales de larga data<\/a> destinadas a evitar que los inmigrantes se conviertan en una &#8220;carga p\u00fablica&#8221;, es decir, que dependan principalmente del apoyo gubernamental, al privarlos de los medios para mantenerse. Las organizaciones sin fines de lucro que antes ayudaban a los reci\u00e9n llegados a adaptarse y establecerse ahora se esfuerzan por brindar ayuda de emergencia, ya que cada vez m\u00e1s familias tienen dificultades para cubrir sus gastos b\u00e1sicos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.linkedin.com\/in\/jaimeberrios\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"560\" height=\"257\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Jaime-copy-2.jpg\" alt=\"\" class=\"wp-image-32093\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Jaime-copy-2.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Jaime-copy-2-300x138.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Jaime-copy-2-150x69.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<p>&#8220;Estamos tratando de reunir fondos para ayudar a las personas, para que no se queden sin hogar. No hay otra alternativa&#8221;, se\u00f1al\u00f3 Courtney Madsen, directora de dise\u00f1o y desarrollo de programas en <a href=\"https:\/\/cwsjerseycity.org\/\">Church World Service<\/a>, una agencia l\u00edder en el reasentamiento de refugiados. &#8220;No nos centramos en la autosuficiencia. Intentamos asegurar que la gente sobreviva&#8221;.<\/p>\n\n\n\n<p>Urbina, quien lleg\u00f3 a Estados Unidos desde Honduras, ha solicitado la residencia permanente. Mientras tanto, sus hijos adultos ayudan a su esposo a pagar la hipoteca.<\/p>\n\n\n\n<p>&#8220;Siempre pagu\u00e9 mis impuestos a tiempo&#8221;, relat\u00f3. &#8220;No creo haber hecho nada malo. Trabajaba duro para mantener a mi familia&#8221;.<\/p>\n\n\n\n<p><strong>En espera de trabajo<\/strong><\/p>\n\n\n\n<p>Urbina cuenta con el Estatus de Protecci\u00f3n Temporal (TPS) desde 1999, una designaci\u00f3n otorgada a personas cuyos pa\u00edses de origen enfrentan condiciones inseguras como guerra o desastres ambientales.<\/p>\n\n\n\n<p>La administraci\u00f3n Trump ha tomado medidas para poner fin al TPS para Honduras y otros 11 pa\u00edses, lo que <a href=\"https:\/\/www.migrationpolicy.org\/article\/trump-2-immigration-1st-year#:~:text=The%20administration%20has%20stripped%20temporary%20legal%20protections%20from%20more%20than%201.5%20million%20humanitarian%20parolees\">afecta a aproximadamente 1.5 millones de personas<\/a> que viven en Estados Unidos. Tambi\u00e9n ha puesto fin a los programas de permiso humanitario para cerca de 1 mill\u00f3n de personas. Estos programas brindaban protecci\u00f3n temporal contra la deportaci\u00f3n y autorizaci\u00f3n de trabajo a personas de pa\u00edses como Cuba, Ucrania y Afganist\u00e1n, pero no ofrec\u00edan una v\u00eda hacia la residencia permanente o la ciudadan\u00eda.<\/p>\n\n\n\n<p>Seg\u00fan declar\u00f3 Joseph B. Edlow, director del Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos (USCIS), <a href=\"https:\/\/www.uscis.gov\/newsroom\/news-releases\/making-america-safe-again-us-citizenship-and-immigration-services-end-of-year-review-demonstrates\">las autoridades afirman estar frenando lo que denominan el uso excesivo de estos programas<\/a>, como parte de una iniciativa m\u00e1s amplia para reforzar los controles migratorios debido a preocupaciones de seguridad y recursos.<\/p>\n\n\n\n<p>&#8220;El USCIS ha adoptado un enfoque de &#8216;Estados Unidos Primero&#8217;, restableciendo el orden, la seguridad, la integridad y la rendici\u00f3n de cuentas en el sistema migratorio estadounidense, garantizando que sirva a los intereses de la naci\u00f3n y proteja y priorice a los estadounidenses sobre los extranjeros&#8221;, afirm\u00f3.<\/p>\n\n\n\n<p>La agencia, dijo, puso fin a las pol\u00edticas de la administraci\u00f3n Biden que estaban &#8220;desmantelando, explotando y socavando el sistema migratorio estadounidense&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"748\" height=\"500\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-12-748x500.jpeg\" alt=\"\" class=\"wp-image-32144\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-12-748x500.jpeg 748w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-12-300x200.jpeg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-12-768x513.jpeg 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-12-150x100.jpeg 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-12-696x465.jpeg 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-12-1068x714.jpeg 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-12.jpeg 1320w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><\/figure>\n\n\n\n<p>Maribel Urbina, inmigrante hondure\u00f1a, coloca sus manos sobre el chaleco que usaba como conductora de autob\u00fas escolar el martes 31 de marzo de 2026. Urbina, quien fue conductora de autob\u00fas escolar durante 21 a\u00f1os, perdi\u00f3 su Estatus de Protecci\u00f3n Temporal y su autorizaci\u00f3n de trabajo cuando la administraci\u00f3n Trump cancel\u00f3 el programa para los hondure\u00f1os. Por motivos de privacidad, Urbina prefiri\u00f3 no publicar su rostro. <em>Foto Julian Leshay Guadalupe\/NorthJersey.com<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/nj.gov\/health\/documents\/parkinsons-flyer-spanish.pdf\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"350\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/DOH-Spanish-banner.jpg\" alt=\"\" class=\"wp-image-32084\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/DOH-Spanish-banner.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/DOH-Spanish-banner-300x188.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/DOH-Spanish-banner-150x94.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<p>El impacto total a\u00fan es incierto. Los tribunales est\u00e1n evaluando diversas impugnaciones legales y, en algunos casos, han revocado o suspendido las \u00f3rdenes de la administraci\u00f3n. Mientras tanto, las personas con protecciones superpuestas, como las solicitudes de asilo pendientes, han podido mantener su estatus legal y sus permisos de trabajo.<\/p>\n\n\n\n<p>Para Urbina, el futuro es incierto. Ha solicitado la residencia permanente patrocinada por sus hijos, que son ciudadanos estadounidenses. Normalmente, una persona puede obtener un permiso de trabajo mientras su solicitud est\u00e1 pendiente, pero su caso se ha estancado debido a una orden de deportaci\u00f3n que, seg\u00fan ella, se emiti\u00f3 hace tres d\u00e9cadas.<\/p>\n\n\n\n<p>&#8220;Quiero seguir contribuyendo y poder trabajar&#8221;, \u200b\u200bafirm\u00f3 Urbina. &#8220;No ped\u00eda ayuda. No ped\u00eda ning\u00fan beneficio. Estaba manteniendo a mi familia y a m\u00ed misma&#8221;.<\/p>\n\n\n\n<p>Otros cambios en las pol\u00edticas han restringido a\u00fan m\u00e1s el acceso al trabajo.<\/p>\n\n\n\n<p>En octubre, el Departamento de Seguridad Nacional <a href=\"https:\/\/www.uscis.gov\/newsroom\/news-releases\/dhs-ends-automatic-extension-of-employment-authorization\">cancel\u00f3 la renovaci\u00f3n autom\u00e1tica<\/a> de los documentos de autorizaci\u00f3n de trabajo para ciertos grupos, incluidos los solicitantes de asilo, los refugiados y los solicitantes de la tarjeta de residencia. Ahora deben volver a solicitarlo, pero se enfrentan a retrasos en el procesamiento que, seg\u00fan defensores y abogados, est\u00e1n provocando interrupciones en el empleo y p\u00e9rdidas de puestos de trabajo. El cambio, seg\u00fan el DHS, ten\u00eda como objetivo aumentar los controles de seguridad y verificaci\u00f3n.<\/p>\n\n\n\n<p>Dos meses despu\u00e9s, el Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos (USCIS, por sus siglas en ingl\u00e9s) redujo la validez de los permisos de trabajo <a href=\"https:\/\/www.uscis.gov\/newsroom\/news-releases\/uscis-increases-screening-vetting-of-aliens-working-in-us#:~:text=The%20maximum%20validity%20period%20for,for%20several%20categories%20of%20aliens%3A\">de cinco a\u00f1os a 18 meses<\/a>.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.fmcsa.dot.gov\/regulations\/non-domiciled-cdl-2026-final-rule-faqs\">Una nueva norma federal<\/a> emitida en febrero tambi\u00e9n proh\u00edbe a los solicitantes de asilo, refugiados y beneficiarios del programa de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA), destinado a inmigrantes que llegaron a Estados Unidos siendo ni\u00f1os, renovar sus licencias de conducir comerciales. El Departamento de Transporte indic\u00f3 que la norma, que afecta a <a href=\"https:\/\/www.fmcsa.dot.gov\/sites\/fmcsa.dot.gov\/files\/2025-09\/Interim%20Final%20Rule_Restoring%20Integrity%20to%20the%20Issuance%20of%20Non-Domiciled%20Commercial%20Drivers%20Licenses.pdf\">aproximadamente 200,000<\/a> conductores de camiones y autobuses, se debe a motivos de seguridad.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.manuelbatistalaw.com\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"257\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/ManuelBatistaSpanish.jpg\" alt=\"\" class=\"wp-image-32095\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/ManuelBatistaSpanish.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/ManuelBatistaSpanish-300x138.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/ManuelBatistaSpanish-150x69.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<p>Otra propuesta federal, publicada en febrero, limitar\u00eda dr\u00e1sticamente la capacidad de los solicitantes de asilo para trabajar en Estados Unidos si se aprueba.<\/p>\n\n\n\n<p><a href=\"https:\/\/public-inspection.federalregister.gov\/2026-03595.pdf\">El borrador de la normativa<\/a> exige la suspensi\u00f3n de las nuevas solicitudes de permisos de asilo hasta que el tiempo de procesamiento se reduzca a 180 d\u00edas o menos. Seg\u00fan el Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos (USCIS), alcanzar ese umbral <a href=\"https:\/\/www.federalregister.gov\/documents\/2026\/02\/23\/2026-03595\/employment-authorization-reform-for-asylum-applicants\">podr\u00eda tardar entre 14 y 173 a\u00f1os<\/a>, a menos que se tomen medidas para acortar el plazo. Defensores de los inmigrantes y <a href=\"https:\/\/www.nycbar.org\/reports\/comment-letter-on-employment-authorization-reform-for-asylum-applicants\/\">abogados<\/a> afirman que esta medida impedir\u00eda que muchos solicitantes de asilo trabajen legalmente mientras sus solicitudes est\u00e1n pendientes.<\/p>\n\n\n\n<p><strong>Adapt\u00e1ndose a los r\u00e1pidos cambios<\/strong><\/p>\n\n\n\n<p>Funcionarios estadounidenses <a href=\"https:\/\/www.uscis.gov\/newsroom\/news-releases\/making-america-safe-again-us-citizenship-and-immigration-services-end-of-year-review-demonstrates\">afirman que estos cambios<\/a> son necesarios para fortalecer la verificaci\u00f3n de antecedentes y la seguridad, y para eliminar el fraude. Afirman que algunas personas han presentado solicitudes de asilo y permisos humanitarios sin fundamento, lo que sobrecarga el sistema de inmigraci\u00f3n.<\/p>\n\n\n\n<p>Los defensores de los inmigrantes se\u00f1alan que las nuevas pol\u00edticas y restricciones perjudican a los migrantes que siguieron los procedimientos legales o que tienen solicitudes de asilo v\u00e1lidas y que ahora tienen dificultades para mantenerse a s\u00ed mismos y a sus familias.<\/p>\n\n\n\n<p>Tanto empleadores como arrendadores y trabajadores se enfrentan a normas que cambian r\u00e1pidamente, lo que crea un clima de incertidumbre que, seg\u00fan los defensores, est\u00e1 desalentando las contrataciones y provocando la p\u00e9rdida de empleos.<\/p>\n\n\n\n<p>Grandes empresas como Walmart y Amazon despidieron preventivamente a empleados con autorizaci\u00f3n de trabajo temporal, seg\u00fan Madsen. Los trabajadores sociales de Church World Service informan que sus clientes tienen dificultades para encontrar trabajo, a pesar de la escasez de mano de obra reportada en sectores como la hosteler\u00eda y la salud.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/ramospodiatry.com\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"257\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Ramos-Spanish560.jpg\" alt=\"\" class=\"wp-image-32096\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Ramos-Spanish560.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Ramos-Spanish560-300x138.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Ramos-Spanish560-150x69.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<p>&#8220;Aseguran que ahora es dif\u00edcil contratar incluso a personas con autorizaci\u00f3n de trabajo v\u00e1lida porque los empleadores temen que algo cambie&#8221;, indic\u00f3 Madsen. &#8220;Existe el temor de infringir las leyes de inmigraci\u00f3n&#8221;.<\/p>\n\n\n\n<p><a href=\"https:\/\/cwsjerseycity.org\/\">Church World Service<\/a> trabaja para informar a sus clientes sobre sus derechos como trabajadores y su elegibilidad para recibir beneficios, y para conectarlos con recursos comunitarios como bancos de alimentos. Madsen afirma que la inseguridad alimentaria es ahora una preocupaci\u00f3n mucho m\u00e1s grave. Algunos se han mostrado reacios a solicitar Medicaid o asistencia alimentaria, incluso cuando cumplen con los requisitos, debido al temor y la confusi\u00f3n sobre las pol\u00edticas federales, explic\u00f3.<\/p>\n\n\n\n<p>&#8220;La necesidad supera con creces nuestra capacidad de recaudaci\u00f3n de fondos&#8221;, indic\u00f3 Madsen. &#8220;Eso es obvio, pero nos estamos enfocando en garantizar que las personas se encuentren seguras y que conozcan sus derechos y en la inseguridad alimentaria&#8221;.<\/p>\n\n\n\n<p>Las nuevas pol\u00edticas, a\u00f1adi\u00f3, parecen dise\u00f1adas para alentar a las personas a &#8220;autodeportarse&#8221; y env\u00edan un mensaje a los dem\u00e1s de que no son bienvenidos, opin\u00f3 Madsen.<\/p>\n\n\n\n<p>&#8220;Est\u00e1n tratando de dificultar las cosas para que la gente decida que no vale la pena quedarse aqu\u00ed&#8221;, dijo. &#8220;Este es su hogar. Se sienten a gusto viviendo aqu\u00ed. Quieren vivir aqu\u00ed. Algunos clientes han intentado venir a Estados Unidos durante a\u00f1os para comenzar una nueva vida&#8221;.<\/p>\n\n\n\n<p><strong>&#8216;No los queremos aqu\u00ed&#8217;<\/strong><\/p>\n\n\n\n<p>Las consecuencias ya se est\u00e1n sintiendo en el \u00e1mbito de la vivienda.<\/p>\n\n\n\n<p><a href=\"https:\/\/interfaithrise.org\/\">Interfaith-RISE<\/a> (Apoyo y Empoderamiento para Refugiados e Inmigrantes), con sede en Highland Park, que ayuda a refugiados, solicitantes de asilo y personas con permiso humanitario, ha visto c\u00f3mo sus clientes han perdido sus empleos en residencias de ancianos, f\u00e1bricas y comercios. Algunos ahora tienen dificultades para pagar el alquiler.<\/p>\n\n\n\n<p>A trav\u00e9s de su organizaci\u00f3n matriz, la Corporaci\u00f3n de Vivienda Asequible de la Iglesia Reformada de Highland Park, la agencia alquila apartamentos a nuevos inmigrantes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"441\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-9.jpeg\" alt=\"\" class=\"wp-image-32141\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-9.jpeg 660w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-9-300x200.jpeg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-9-150x100.jpeg 150w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/figure>\n\n\n\n<p>Seth Kaper-Dale, pastor de la Iglesia Reformada de Highland Park, conversa con Yvonne Mukayisenga, refugiada de la Rep\u00fablica Democr\u00e1tica del Congo. <em>(Foto de archivo)<\/em><\/p>\n\n\n\n<p>&#8220;Actualmente alquilamos 200 apartamentos a haitianos, afganos, congole\u00f1os, solicitantes de asilo y personas que no han tenido problemas para pagar el alquiler durante a\u00f1os&#8221;, rese\u00f1\u00f3 el reverendo Seth Kaper-Dale, director ejecutivo de la corporaci\u00f3n de vivienda y fundador de Interfaith-RISE.&nbsp;<\/p>\n\n\n\n<p>Ahora algunos tienen tres o cuatro meses de alquiler atrasados&#8221;, se\u00f1al\u00f3 Kaper-Dale. &#8220;\u00bfPor qu\u00e9? Porque perdieron su trabajo debido a un problema con sus EAD (Documentos de Autorizaci\u00f3n de Empleo, por sus siglas en ingl\u00e9s)&#8221;.<\/p>\n\n\n\n<p>Al dificultar el acceso al trabajo, el gobierno se aleja de su objetivo, consagrado en la pol\u00edtica federal para las agencias de reasentamiento de refugiados, de lograr la autosuficiencia de los reci\u00e9n llegados, afirm\u00f3 Kaper-Dale.<\/p>\n\n\n\n<p>&#8220;En lugar de centrarnos en la autosuficiencia, ahora todo gira en torno a la autoprotecci\u00f3n. Cualquier cosa con tal de ayudar a la gente a obtener un permiso de trabajo&#8221;, afirm\u00f3 Kaper-Dale, destacando que la agencia ampli\u00f3 los servicios de asistencia legal para ayudar a las personas a solicitar el ajuste de su estatus. &#8220;Estamos enviando un mensaje totalmente diferente: que no los queremos aqu\u00ed. Sin embargo, la gente tiene que sobrevivir&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inthepinkroom.com?utm_source=americanonewspaper&amp;utm_medium=referral&amp;utm_campaign=general\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"313\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/ThePinkRoom-copy-1.jpg\" alt=\"The Pink Room\" class=\"wp-image-31924\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/ThePinkRoom-copy-1.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/ThePinkRoom-copy-1-300x168.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/ThePinkRoom-copy-1-150x84.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><figcaption class=\"wp-element-caption\">The Pink Room <\/figcaption><\/figure>\n\n\n\n<p><strong>Aumento de la necesidad<\/strong><\/p>\n\n\n\n<p>Organizaciones sin fines de lucro, grupos comunitarios y religiosos afirman que la falta de permisos de trabajo es solo uno de los factores que incrementan la necesidad entre las comunidades inmigrantes a las que sirven. Las detenciones, el temor al arresto y la p\u00e9rdida de beneficios p\u00fablicos han agravado la crisis, dejando a las familias con dificultades para cubrir necesidades b\u00e1sicas como alimentos, alquiler y atenci\u00f3n m\u00e9dica.<\/p>\n\n\n\n<p>&#8220;Les hemos quitado la posibilidad de trabajar y tambi\u00e9n hemos reducido su acceso a servicios, atenci\u00f3n m\u00e9dica y educaci\u00f3n&#8221;, se\u00f1al\u00f3 Itzel Hern\u00e1ndez, organizadora de derechos de los inmigrantes de <a href=\"https:\/\/afsc.org\/programs\/new-jersey-immigrant-rights\">American Friends Service Committee<\/a> (AFSC). &#8220;En la pr\u00e1ctica, los estamos deshumanizando&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"375\" height=\"500\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-10-375x500.jpeg\" alt=\"\" class=\"wp-image-32142\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-10-375x500.jpeg 375w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-10-225x300.jpeg 225w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-10-150x200.jpeg 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-10-300x400.jpeg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-10.jpeg 600w\" sizes=\"(max-width: 375px) 100vw, 375px\" \/><\/figure>\n\n\n\n<p>El reverendo Bol\u00edvar Flores, vicepresidente de la Coalici\u00f3n de Pastores Latinos de Nueva Jersey, distribuye alimentos en Newark el 6 de marzo de 2026. <em>Cortes\u00eda del reverendo Bol\u00edvar Flores<\/em><\/p>\n\n\n\n<p>AFSC ha ampliado sus programas de informaci\u00f3n sobre derechos para que las personas &#8220;tengan la informaci\u00f3n necesaria para continuar con sus actividades diarias&#8221;.<\/p>\n\n\n\n<p>Jennifer Gill, directora ejecutiva de <a href=\"https:\/\/oneworldonelovenj.org\/\">One World One Love<\/a>, con sede en Elizabeth, tambi\u00e9n ha presenciado de primera mano la presi\u00f3n que sufren las familias. Los beneficiarios de permisos humanitarios, los solicitantes de asilo y los titulares del Estatus de Protecci\u00f3n Temporal (TPS) han perdido su autorizaci\u00f3n de trabajo, afirm\u00f3. Los refugiados, que constituyen la mayor\u00eda de los clientes del grupo, a\u00fan conservan sus permisos de trabajo, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>&#8220;Ha sido un momento realmente dif\u00edcil para muchas familias e individuos que han perdido su autorizaci\u00f3n de trabajo o temen perderla&#8221;, se\u00f1al\u00f3 Gill. &#8220;Quieren ser productivos. Quieren contribuir. No quieren quedarse en casa sin hacer nada&#8221;.<\/p>\n\n\n\n<p>One World One Love contin\u00faa ofreciendo tutor\u00edas de idiomas, capacitaci\u00f3n en inform\u00e1tica y orientaci\u00f3n laboral, con la esperanza de &#8220;mantener el enfoque en un futuro positivo para que, cuando llegue el momento, est\u00e9n preparados&#8221;.<\/p>\n\n\n\n<p>Las agencias que ayudan a los inmigrantes afirman que dependen cada vez m\u00e1s de voluntarios y donaciones de la comunidad para satisfacer las crecientes necesidades, mientras que las instituciones religiosas tambi\u00e9n est\u00e1n aumentando su apoyo.<\/p>\n\n\n\n<p>La <a href=\"https:\/\/latinopastorsnj.com\/\">Coalici\u00f3n de Pastores y Ministros Latinos de Nueva Jersey<\/a>, que representa a 473 iglesias, lanz\u00f3 una l\u00ednea directa de ayuda para inmigrantes en enero. Cientos de personas han llamado buscando asistencia legal u otro tipo de apoyo, incluyendo personas que han perdido sus permisos de trabajo y otros indocumentados, dijo el reverendo Bol\u00edvar Flores, vicepresidente de la <a href=\"https:\/\/latinopastorsnj.com\/\">Coalici\u00f3n de Pastores y Ministros Latinos de Nueva Jersey<\/a>.<\/p>\n\n\n\n<p>El grupo de pastores distribuye 40,000 libras de alimentos al mes, agreg\u00f3. Antes, las provisiones duraban una o dos semanas, pero ahora se agotan en uno o dos d\u00edas.<\/p>\n\n\n\n<p>&#8220;Vienen a la iglesia porque necesitan respuestas espirituales&#8221;, dijo Flores. &#8220;A veces, vienen porque necesitan comida, algo para comer, o porque tienen hijos. En este momento, estamos recaudando fondos para ayudar a las personas a pagar el alquiler y las facturas de servicios p\u00fablicos. Personalmente, esto es desgarrador. Seguimos orando y tratando a nuestra comunidad con dignidad y respeto&#8221;.<\/p>\n\n\n\n<p>En Englewood, Urbina coment\u00f3 que se ha sentido deprimida por la p\u00e9rdida de su trabajo y la incertidumbre sobre su caso migratorio. Tras m\u00e1s de tres d\u00e9cadas en el pa\u00eds, desea quedarse con su familia y volver a trabajar.<\/p>\n\n\n\n<p>&#8220;Mi sue\u00f1o es recuperar mi licencia y poder conducir de nuevo&#8221;, dijo, &#8220;ya sea con una extensi\u00f3n del TPS o con la tarjeta de residencia. Lo \u00fanico que quiero es seguir contribuyendo y poder trabajar&#8221;.<\/p>\n\n\n\n<p><strong><em>Esta traducci\u00f3n fue proporcionada por <\/em><\/strong><a href=\"https:\/\/reportehispano.com\/\"><strong><em>Reporte Hispano<\/em><\/strong><\/a><strong><em> en asociaci\u00f3n con el Centro de Medios Cooperativos de la Universidad Estatal de Montclair, y cuenta con el apoyo financiero del Consorcio de Informaci\u00f3n C\u00edvica de NJ. La historia fue escrita originalmente en ingl\u00e9s por <\/em><\/strong><a href=\"https:\/\/www.northjersey.com\/story\/news\/2026\/05\/05\/trump-immigration-rules-cost-immigrants-jobs\/89354271007\/\"><strong><em>NorthJersey.com<\/em><\/strong><\/a><strong><em> y se vuelve a publicar en virtud de un acuerdo especial para compartir contenido a trav\u00e9s del Servicio de noticias de traducci\u00f3n al espa\u00f1ol de NJ News Commons.<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"165\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/Tayakanlogo560.jpg\" alt=\"\" class=\"wp-image-31948\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/Tayakanlogo560.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/Tayakanlogo560-300x88.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/Tayakanlogo560-150x44.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/figure>\n\n\n\n<p><strong><em>This translation was provided by <\/em><\/strong><a href=\"https:\/\/reportehispano.com\/\"><strong><em>Reporte Hispano<\/em><\/strong><\/a><strong><em>, in partnership with Montclair State University\u2019s Center for Cooperative Media and is supported financially by the NJ Civic Information Consortium. The story was originally written in English by <\/em><\/strong><a href=\"https:\/\/www.northjersey.com\/story\/news\/2026\/05\/05\/trump-immigration-rules-cost-immigrants-jobs\/89354271007\/\"><strong><em>NorthJersey.com<\/em><\/strong><\/a><strong><em> and is republished under a special content-sharing agreement through NJ News Commons\u2019 Spanish Translation News Service.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inmigrante hondure\u00f1a perdi\u00f3 su derecho a trabajar Por Hannan Adely, NorthJersey.com Durante 21 a\u00f1os, Maribel Urbina manej\u00f3 un autob\u00fas escolar de 54 pasajeros. Recorri\u00f3 las calles de la ciudad de Nueva York y las carreteras suburbanas. Transportaba a los estudiantes desde y hacia la escuela Dwight-Englewood. Los llevaba a excursiones escolares, al teatro y al [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":32143,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false,"token":"eyJpbWciOiJodHRwczpcL1wvd3d3LmFtZXJpY2Fub25ld3NwYXBlci5jb21cL2VzXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wNVwvaW1hZ2UtMTEtNzUweDUwMC5qcGVnIiwidHh0IjoiTWFuZWpcdTAwZjMgdW4gYXV0b2JcdTAwZmFzIGVzY29sYXIgZHVyYW50ZSAyMSBhXHUwMGYxb3MuIEFob3JhIHBlcmRpXHUwMGYzIHN1IGF1dG9yaXphY2lcdTAwZjNuIGxlZ2FsIHBhcmEgdHJhYmFqYXIiLCJ0ZW1wbGF0ZSI6ImhpZ2h3YXkiLCJmb250IjoiIiwiYmxvZ19pZCI6MjI4NjE5NTc0fQ.tkq8GwC3EV841IWPqNb94ZWpdotOcdAfAJZv2C_zo2EMQ"},"version":2,"media_source":"featured-image","attached_media":[{"id":32143,"url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg","type":"image\/jpeg"}]},"_wpas_customize_per_network":false},"categories":[1173,196,246],"tags":[],"class_list":{"0":"post-32140","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-administracion-trump","8":"category-immigration","9":"category-new-jersey"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Manej\u00f3 un autob\u00fas escolar durante 21 a\u00f1os. Ahora perdi\u00f3 su autorizaci\u00f3n legal para trabajar - Americano Newspaper<\/title>\n<meta name=\"description\" content=\"Durante 21 a\u00f1os, Maribel Urbina manej\u00f3 un autob\u00fas escolar de 54 pasajeros.Recorri\u00f3 las calles de la ciudad de Nueva York y las carreteras suburbanas. Transportaba a los estudiantes desde y hacia la escuela Dwight-Englewood. Los llevaba a excursiones escolares, al teatro y al zool\u00f3gico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manej\u00f3 un autob\u00fas escolar durante 21 a\u00f1os. Ahora perdi\u00f3 su autorizaci\u00f3n legal para trabajar\" \/>\n<meta property=\"og:description\" content=\"Durante 21 a\u00f1os, Maribel Urbina manej\u00f3 un autob\u00fas escolar de 54 pasajeros.Recorri\u00f3 las calles de la ciudad de Nueva York y las carreteras suburbanas. Transportaba a los estudiantes desde y hacia la escuela Dwight-Englewood. Los llevaba a excursiones escolares, al teatro y al zool\u00f3gico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/\" \/>\n<meta property=\"og:site_name\" content=\"Americano Newspaper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AmericanoNewspaper\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T13:28:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:28:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1320\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Author\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Author\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/\"},\"author\":{\"name\":\"Author\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/person\\\/8967f6b8af7e37bcbbe61f68580ff088\"},\"headline\":\"Manej\u00f3 un autob\u00fas escolar durante 21 a\u00f1os. Ahora perdi\u00f3 su autorizaci\u00f3n legal para trabajar\",\"datePublished\":\"2026-05-13T13:28:11+00:00\",\"dateModified\":\"2026-05-13T13:28:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/\"},\"wordCount\":2726,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image-11.jpeg\",\"articleSection\":[\"Administraci\u00f3n Trump\",\"Inmigraci\u00f3n\",\"New Jersey\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/\",\"name\":\"Manej\u00f3 un autob\u00fas escolar durante 21 a\u00f1os. Ahora perdi\u00f3 su autorizaci\u00f3n legal para trabajar - Americano Newspaper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image-11.jpeg\",\"datePublished\":\"2026-05-13T13:28:11+00:00\",\"dateModified\":\"2026-05-13T13:28:17+00:00\",\"description\":\"Durante 21 a\u00f1os, Maribel Urbina manej\u00f3 un autob\u00fas escolar de 54 pasajeros.Recorri\u00f3 las calles de la ciudad de Nueva York y las carreteras suburbanas. Transportaba a los estudiantes desde y hacia la escuela Dwight-Englewood. Los llevaba a excursiones escolares, al teatro y al zool\u00f3gico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image-11.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image-11.jpeg\",\"width\":1320,\"height\":880,\"caption\":\"Maribel Urbina, inmigrante hondure\u00f1a, se sienta en su cama con el chaleco que usaba como conductora de autob\u00fas escolar el martes 31 de marzo de 2026. Urbina, quien fue conductora de autob\u00fas escolar durante 21 a\u00f1os, perdi\u00f3 su Estatus de Protecci\u00f3n Temporal y su autorizaci\u00f3n de trabajo cuando la administraci\u00f3n Trump cancel\u00f3 el programa para los hondure\u00f1os. Por motivos de privacidad, Urbina prefiri\u00f3 no publicar su rostro. Foto Julian Leshay Guadalupe\\\/NorthJersey.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/immigration\\\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manej\u00f3 un autob\u00fas escolar durante 21 a\u00f1os. Ahora perdi\u00f3 su autorizaci\u00f3n legal para trabajar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\",\"name\":\"Americano Newspaper\",\"description\":\"The Hispanic Newspaper of New Jersey.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\",\"name\":\"Americano Newspaper\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AmericanoLogoCircle.comCircle2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AmericanoLogoCircle.comCircle2.jpg\",\"width\":600,\"height\":600,\"caption\":\"Americano Newspaper\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AmericanoNewspaper\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/person\\\/8967f6b8af7e37bcbbe61f68580ff088\",\"name\":\"Author\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103\",\"caption\":\"Author\"},\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/author\\\/americano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Manej\u00f3 un autob\u00fas escolar durante 21 a\u00f1os. Ahora perdi\u00f3 su autorizaci\u00f3n legal para trabajar - Americano Newspaper","description":"Durante 21 a\u00f1os, Maribel Urbina manej\u00f3 un autob\u00fas escolar de 54 pasajeros.Recorri\u00f3 las calles de la ciudad de Nueva York y las carreteras suburbanas. Transportaba a los estudiantes desde y hacia la escuela Dwight-Englewood. Los llevaba a excursiones escolares, al teatro y al zool\u00f3gico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/","og_locale":"en_US","og_type":"article","og_title":"Manej\u00f3 un autob\u00fas escolar durante 21 a\u00f1os. Ahora perdi\u00f3 su autorizaci\u00f3n legal para trabajar","og_description":"Durante 21 a\u00f1os, Maribel Urbina manej\u00f3 un autob\u00fas escolar de 54 pasajeros.Recorri\u00f3 las calles de la ciudad de Nueva York y las carreteras suburbanas. Transportaba a los estudiantes desde y hacia la escuela Dwight-Englewood. Los llevaba a excursiones escolares, al teatro y al zool\u00f3gico.","og_url":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/","og_site_name":"Americano Newspaper","article_publisher":"https:\/\/www.facebook.com\/AmericanoNewspaper\/","article_published_time":"2026-05-13T13:28:11+00:00","article_modified_time":"2026-05-13T13:28:17+00:00","og_image":[{"width":1320,"height":880,"url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg","type":"image\/jpeg"}],"author":"Author","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Author","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/#article","isPartOf":{"@id":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/"},"author":{"name":"Author","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/person\/8967f6b8af7e37bcbbe61f68580ff088"},"headline":"Manej\u00f3 un autob\u00fas escolar durante 21 a\u00f1os. Ahora perdi\u00f3 su autorizaci\u00f3n legal para trabajar","datePublished":"2026-05-13T13:28:11+00:00","dateModified":"2026-05-13T13:28:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/"},"wordCount":2726,"commentCount":0,"publisher":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#organization"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg","articleSection":["Administraci\u00f3n Trump","Inmigraci\u00f3n","New Jersey"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/","url":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/","name":"Manej\u00f3 un autob\u00fas escolar durante 21 a\u00f1os. Ahora perdi\u00f3 su autorizaci\u00f3n legal para trabajar - Americano Newspaper","isPartOf":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/#primaryimage"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg","datePublished":"2026-05-13T13:28:11+00:00","dateModified":"2026-05-13T13:28:17+00:00","description":"Durante 21 a\u00f1os, Maribel Urbina manej\u00f3 un autob\u00fas escolar de 54 pasajeros.Recorri\u00f3 las calles de la ciudad de Nueva York y las carreteras suburbanas. Transportaba a los estudiantes desde y hacia la escuela Dwight-Englewood. Los llevaba a excursiones escolares, al teatro y al zool\u00f3gico.","breadcrumb":{"@id":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/#primaryimage","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg","width":1320,"height":880,"caption":"Maribel Urbina, inmigrante hondure\u00f1a, se sienta en su cama con el chaleco que usaba como conductora de autob\u00fas escolar el martes 31 de marzo de 2026. Urbina, quien fue conductora de autob\u00fas escolar durante 21 a\u00f1os, perdi\u00f3 su Estatus de Protecci\u00f3n Temporal y su autorizaci\u00f3n de trabajo cuando la administraci\u00f3n Trump cancel\u00f3 el programa para los hondure\u00f1os. Por motivos de privacidad, Urbina prefiri\u00f3 no publicar su rostro. Foto Julian Leshay Guadalupe\/NorthJersey.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.americanonewspaper.com\/es\/immigration\/manejo-un-autobus-escolar-durante-21-anos-ahora-perdio-su-autorizacion-legal-para-trabajar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.americanonewspaper.com\/es\/"},{"@type":"ListItem","position":2,"name":"Manej\u00f3 un autob\u00fas escolar durante 21 a\u00f1os. Ahora perdi\u00f3 su autorizaci\u00f3n legal para trabajar"}]},{"@type":"WebSite","@id":"https:\/\/www.americanonewspaper.com\/es\/#website","url":"https:\/\/www.americanonewspaper.com\/es\/","name":"Americano Newspaper","description":"The Hispanic Newspaper of New Jersey.","publisher":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.americanonewspaper.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.americanonewspaper.com\/es\/#organization","name":"Americano Newspaper","url":"https:\/\/www.americanonewspaper.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2024\/05\/AmericanoLogoCircle.comCircle2.jpg","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2024\/05\/AmericanoLogoCircle.comCircle2.jpg","width":600,"height":600,"caption":"Americano Newspaper"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AmericanoNewspaper\/"]},{"@type":"Person","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/person\/8967f6b8af7e37bcbbe61f68580ff088","name":"Author","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103","caption":"Author"},"url":"https:\/\/www.americanonewspaper.com\/es\/author\/americano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg","featured_image_urls":{"full":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg",1320,880,false],"thumbnail":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-250x250.jpeg",250,250,true],"medium":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-300x200.jpeg",300,200,true],"medium_large":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-768x512.jpeg",696,464,true],"large":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-750x500.jpeg",696,464,true],"1536x1536":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg",1320,880,false],"2048x2048":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg",1320,880,false],"td_150x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-150x100.jpeg",150,100,true],"td_218x150":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-218x150.jpeg",218,150,true],"td_300x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-300x200.jpeg",300,200,true],"td_324x400":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-324x400.jpeg",324,400,true],"td_485x360":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-485x360.jpeg",485,360,true],"td_696x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-696x464.jpeg",696,464,true],"td_1068x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-1068x712.jpeg",1068,712,true],"td_1920x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11.jpeg",1320,880,false],"bdpp-medium":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-11-640x480.jpeg",640,480,true]},"author_info":{"display_name":"Author","author_link":"https:\/\/www.americanonewspaper.com\/es\/author\/americano\/"},"category_info":"<a href=\"https:\/\/www.americanonewspaper.com\/es\/category\/donald-trump\/administracion-trump\/\" rel=\"category tag\">Administraci\u00f3n Trump<\/a> <a href=\"https:\/\/www.americanonewspaper.com\/es\/category\/immigration\/\" rel=\"category tag\">Inmigraci\u00f3n<\/a> <a href=\"https:\/\/www.americanonewspaper.com\/es\/category\/new-jersey\/\" rel=\"category tag\">New Jersey<\/a>","tag_info":"New Jersey","comment_count":"0","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/32140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/comments?post=32140"}],"version-history":[{"count":1,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/32140\/revisions"}],"predecessor-version":[{"id":32145,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/32140\/revisions\/32145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/media\/32143"}],"wp:attachment":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/media?parent=32140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/categories?post=32140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/tags?post=32140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}