{"id":32126,"date":"2026-05-12T21:24:11","date_gmt":"2026-05-13T01:24:11","guid":{"rendered":"https:\/\/www.americanonewspaper.com\/es\/?p=32126"},"modified":"2026-05-12T21:24:18","modified_gmt":"2026-05-13T01:24:18","slug":"los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal","status":"publish","type":"post","link":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/","title":{"rendered":"Los centros de servicio para latinas en NJ enfrentan fuertes recortes en la ayuda estatal"},"content":{"rendered":"\n<p>Por Sophie Nieto-Mu\u00f1oz, New Jersey Monitor<\/p>\n\n\n\n<p class=\"dropcapp3\">Los centros financiados por el estado que brindan recursos de empleo y otros servicios para latinas ver\u00edan un recorte del 80% bajo el presupuesto propuesto por la gobernadora Mikie Sherrill, un cambio que obligar\u00eda a cerrar tres centros y eliminar servicios para miles de latinas en ocho condados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/ggllawyers.com\/es\/new-jersey-personal-injury-and-workers-compensation-lawyer\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img fetchpriority=\"high\" decoding=\"async\" width=\"560\" height=\"269\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/GGlSpanish-1.jpg\" alt=\"Abogados de Accidentes\" class=\"wp-image-32092\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/GGlSpanish-1.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/GGlSpanish-1-300x144.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/GGlSpanish-1-150x72.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><figcaption class=\"wp-element-caption\">Abogados de Accidentes<\/figcaption><\/figure>\n\n\n\n<p>El recorte propuesto ha puesto en alerta a la Latino Action Network Foundation, que administra el programa.<\/p>\n\n\n\n<p>&#8220;El costo humano de esta propuesta no puede ser subestimado. Reducir la financiaci\u00f3n a este nivel desmantelar\u00eda efectivamente el puente hacia la clase media para la mitad de las mujeres a las que servimos&#8221;, afirm\u00f3 Jesselly De La Cruz, directora ejecutiva de la fundaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>La propuesta de presupuesto de Sherrill solicita $535,000 en ayuda estatal para los Hispanic Women\u2019s Resource Centers (Centros de Recursos para Mujeres Hispanas), un recorte de m\u00e1s de $2 millones para los <a href=\"https:\/\/www.lanfoundation.org\/empowering-latinas\">programas<\/a>, que dependen de los fondos estatales. El recorte, si es aprobado por los legisladores estatales, reducir\u00eda el alcance anual del programa de m\u00e1s de 9,000 mujeres a menos de 2,000, y eliminar\u00eda la programaci\u00f3n en el Condado de Passaic y en el sur de Nueva Jersey, dijo De La Cruz.<\/p>\n\n\n\n<p>Los centros, establecidos por la legislaci\u00f3n estatal en 1991, actualmente operan en 11 condados. Proporcionan una variedad de servicios, incluyendo talleres de educaci\u00f3n financiera, capacitaci\u00f3n laboral, servicios de ingl\u00e9s, desarrollo de peque\u00f1os negocios, intervenci\u00f3n en casos de violencia dom\u00e9stica y algunos servicios de salud mental.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.linkedin.com\/in\/jaimeberrios\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"560\" height=\"257\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Jaime-copy-2.jpg\" alt=\"\" class=\"wp-image-32093\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Jaime-copy-2.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Jaime-copy-2-300x138.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Jaime-copy-2-150x69.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<p>De La Cruz expres\u00f3 que parte de la raz\u00f3n por la que se fundaron estos centros fue para ayudar a cerrar la brecha salarial. Las latinas en Nueva Jersey tienen la segunda brecha salarial m\u00e1s grande del pa\u00eds, <a href=\"https:\/\/smlr.rutgers.edu\/sites\/default\/files\/Documents\/Centers\/CWW\/Publications\/LANF_Report_March2023.pdf\">seg\u00fan un estudio de 2023<\/a> del Centro para Mujeres y Trabajo de Rutgers, financiado por la Latino Action Network Foundation.&nbsp;<\/p>\n\n\n\n<p>El Estado Jard\u00edn alberga a m\u00e1s de 2.2 millones de latinos e hispanos, lo que representa casi una cuarta parte de la poblaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>El Departamento de Trabajo del estado supervisa centros de carrera integrales en todo el estado, pero De La Cruz se\u00f1al\u00f3 que los Centros de Recursos para Mujeres Hispanas hacen m\u00e1s porque &#8220;estos programas son parte del fortalecimiento de las familias y los ni\u00f1os&#8221;. Coment\u00f3 que ofrecen clases que ense\u00f1an desde defensa legislativa hasta propiedad de peque\u00f1as empresas y sastrer\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-7-750x500.jpeg\" alt=\"\" class=\"wp-image-32127\" style=\"width:560px\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-7-750x500.jpeg 750w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-7-300x200.jpeg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-7-768x512.jpeg 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-7-1536x1025.jpeg 1536w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-7-150x100.jpeg 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-7-696x464.jpeg 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-7-1068x712.jpeg 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-7-1920x1281.jpeg 1920w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/image-7.jpeg 2048w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p>La gobernadora Mikie Sherrill ofrece su primer discurso presupuestario ante la Legislatura en la Casa de Estado de Trenton el 10 de marzo de 2026. <em>(Foto de Anne-Marie Caruso\/New Jersey Monitor)<\/em><\/p>\n\n\n\n<p>Sherrill, una dem\u00f3crata que asumi\u00f3 el cargo en enero, ha propuesto un <a href=\"https:\/\/newjerseymonitor.com\/2026\/03\/10\/gov-sherrill-proposes-record-60-7b-in-spending-in-first-budget-address\/\">plan de gastos de $60.7 mil millones<\/a> que ahora est\u00e1 en manos de los legisladores. Aunque aumenta el gasto general con respecto al presupuesto del a\u00f1o en curso, ofrece recortes a m\u00faltiples programas que Sherrill afirma son necesarios para reducir un d\u00e9ficit presupuestario de varios miles de millones de d\u00f3lares. Los legisladores deben devolver un presupuesto finalizado a Sherrill para su firma antes del 1 de julio.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/nj.gov\/health\/documents\/parkinsons-flyer-spanish.pdf\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"350\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/DOH-Spanish-banner.jpg\" alt=\"\" class=\"wp-image-32084\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/DOH-Spanish-banner.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/DOH-Spanish-banner-300x188.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/DOH-Spanish-banner-150x94.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<p>Sherrill le dijo a los legisladores en marzo que si quieren ver un financiamiento adicional para servicios y programas, deber\u00edan sugerir otros elementos en el presupuesto que deber\u00edan recortarse para mantener el nivel de gasto.&nbsp;<\/p>\n\n\n\n<p>El recorte propuesto a los Centros de Recursos para Mujeres Hispanas se produce en un momento en la administraci\u00f3n Trump ha intensificado las medidas de control de la inmigraci\u00f3nen todo el pa\u00eds, incluido Nueva Jersey. Esto ha aumentado la demanda de los servicios que los centros ofrecen, seg\u00fan se\u00f1al\u00f3 Paola Mar\u00edn, subdirectora de Community Affairs and Resource Center (Centro de Asuntos Comunitarios y Recursos), uno de los Centros de Recursos para Mujeres Hispanas que tiene oficinas en Asbury Park, Lakewood, Freehold y Long Branch.&nbsp;<\/p>\n\n\n\n<p>&#8220;El estr\u00e9s y la discriminaci\u00f3n, el perfil racial, ha sido horr\u00edfico&#8221;, expres\u00f3. &#8220;Hemos recibido llamadas de clientes que llaman y dicen: Oye, ten\u00eda una cita con ustedes, pero no voy a poder asistir porque ICE est\u00e1 aqu\u00ed hoy, y acaban de llevarse a un amigo m\u00edo o a mi esposo&#8221;, dijo. &#8220;Incluso recoger a sus hijos en la escuela es algo enorme. Definitivamente nos estamos poniendo muy creativos con lo que podemos hacer para seguir sirviendo a nuestra gente&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.manuelbatistalaw.com\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"257\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/ManuelBatistaSpanish.jpg\" alt=\"\" class=\"wp-image-32095\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/ManuelBatistaSpanish.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/ManuelBatistaSpanish-300x138.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/ManuelBatistaSpanish-150x69.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<p>Ana Jezidzic, directora del programa en Centro de Asuntos Comunitarios y Recursos, asegur\u00f3 que los centros no est\u00e1n abiertos solo para mujeres latinas.<\/p>\n\n\n\n<p>Jezidzic record\u00f3 a una clienta cuyo esposo, un rescatista del 11 de septiembre, estaba enfermo de c\u00e1ncer, y la mujer lleg\u00f3 al centro con una pila de facturas sin abrir y documentos de ejecuci\u00f3n hipotecaria que no entend\u00eda, ya que nunca hab\u00eda manejado las finanzas del hogar. El personal la ayud\u00f3 a navegar los tr\u00e1mites, inscribirse en clases de ingl\u00e9s y cursos de computaci\u00f3n, y eventualmente a ayudar a sus hijos a postularse a la universidad. Se\u00f1al\u00f3 esta historia como una raz\u00f3n por la cual las personas deber\u00edan ver este financiamiento como &#8220;una inversi\u00f3n, no un gasto&#8221;.<\/p>\n\n\n\n<p>&#8220;Recortar este financiamiento es como cortar la rama en la que est\u00e1s sentado&#8221;, dijo Jezidzic. &#8220;Eventualmente, vas a caerte. Estamos invirtiendo en las personas, en su educaci\u00f3n, y en lo que eso traer\u00e1 a la comunidad, a la sociedad&#8221;.<\/p>\n\n\n\n<p>Esta no es la primera vez que el programa enfrenta una lucha presupuestaria. El financiamiento fue eliminado bajo el gobernador Chris Christie, un republicano, cuando asumi\u00f3 el cargo, y tom\u00f3 seis a\u00f1os restablecerlo despu\u00e9s de un impulso bipartidista por parte de los legisladores. El predecesor de Sherrill, Phil Murphy (dem\u00f3crata), tambi\u00e9n <a href=\"https:\/\/www.njspotlightnews.org\/2024\/04\/nj-latino-action-network-says-proposed-budget-cut-imperils-hispanic-womens-resource-centers\/\">propuso algunos recortes<\/a> que fueron revertidos antes de que se aprobaran los presupuestos finales. Pero los defensores y los trabajadores afirman que la reducci\u00f3n propuesta este a\u00f1o es mucho mayor de lo que han visto antes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/ramospodiatry.com\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"257\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Ramos-Spanish560.jpg\" alt=\"\" class=\"wp-image-32096\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Ramos-Spanish560.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Ramos-Spanish560-300x138.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Ramos-Spanish560-150x69.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<p>Un portavoz de Sherrill no coment\u00f3 sobre los recortes propuestos. Su administraci\u00f3n ha dicho en respuesta a otros recortes que est\u00e1 abordando un d\u00e9ficit estructural de $3 mil millones y haciendo m\u00e1s de $700 millones en reducciones al gasto estatal.&nbsp;<\/p>\n\n\n\n<p>De La Cruz se\u00f1al\u00f3 que, aunque entiende que el estado necesita encontrar maneras de ahorrar dinero, los recortes propuestos a los centros socavan las posiciones de Sherrill sobre inmigraci\u00f3n. La gobernadora ha utilizado su oficina para contrarrestar el esfuerzo de deportaci\u00f3n masiva de la administraci\u00f3n Trump, incluyendo la firma de una ley que limita la capacidad de la polic\u00eda de Nueva Jersey para <a href=\"https:\/\/newjerseymonitor.com\/2026\/03\/25\/gov-sherrill-signs-bills-immigration-enforcement\/\">cooperar con agentes federales de inmigraci\u00f3n<\/a> y demandar al gobierno federal por sus planes de abrir un centro de <a href=\"https:\/\/newjerseymonitor.com\/2026\/03\/20\/nj-roxbury-sue-trump-ice-warehouse\/\">detenci\u00f3n de migrantes en Roxbury.&nbsp;<\/a><\/p>\n\n\n\n<p>&#8220;Sin estos programas, hay recursos limitados para que las familias llamen y personas que los ayuden a averiguar qu\u00e9 hacer inmediatamente despu\u00e9s de una detenci\u00f3n, cuando se ha perdido al sost\u00e9n de la familia&#8221;, dijo De La Cruz.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/inthepinkroom.com?utm_source=americanonewspaper&amp;utm_medium=referral&amp;utm_campaign=general\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"313\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/ThePinkRoom-copy-1.jpg\" alt=\"The Pink Room\" class=\"wp-image-31924\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/ThePinkRoom-copy-1.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/ThePinkRoom-copy-1-300x168.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/ThePinkRoom-copy-1-150x84.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><figcaption class=\"wp-element-caption\">The Pink Room <\/figcaption><\/figure>\n\n\n\n<p><strong><em>Esta traducci\u00f3n fue proporcionada por <\/em><\/strong><a href=\"https:\/\/ellatinonews.us\/\"><strong><em>El Latino News<\/em><\/strong><\/a><strong><em>, en asociaci\u00f3n con el Centro de Medios Cooperativos de la Universidad Estatal de Montclair, y cuenta con el apoyo financiero del Consorcio de Informaci\u00f3n C\u00edvica de NJ. La historia fue escrita originalmente en ingl\u00e9s por <\/em><\/strong><a href=\"https:\/\/newjerseymonitor.com\/2026\/05\/04\/latina-centers-nj-state-aid-cuts\/\"><strong><em>New Jersey Monitor<\/em><\/strong><\/a><strong><em> y se vuelve a publicar en virtud de un acuerdo especial para compartir contenido a trav\u00e9s del Servicio de noticias de traducci\u00f3n al espa\u00f1ol de NJ News Commons.<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/tayakan.com\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"165\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/Tayakanlogo560.jpg\" alt=\"\" class=\"wp-image-31948\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/Tayakanlogo560.jpg 560w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/Tayakanlogo560-300x88.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/04\/Tayakanlogo560-150x44.jpg 150w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<p><strong><em>This translation was provided by <\/em><\/strong><a href=\"https:\/\/ellatinonews.us\/\"><strong><em>El Latino News<\/em><\/strong><\/a><strong><em>, in association with the Center for Cooperative Media at Montclair State University, and is financially supported by the NJ Civic Information Consortium. The story was originally written in English by <\/em><\/strong><a href=\"https:\/\/newjerseymonitor.com\/2026\/05\/04\/latina-centers-nj-state-aid-cuts\/\"><strong><em>New Jersey Monitor<\/em><\/strong><\/a><strong><em> and is republished under a special content-sharing agreement through the NJ News Commons&#8217; Spanish Translation News Service.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Sophie Nieto-Mu\u00f1oz, New Jersey Monitor Los centros financiados por el estado que brindan recursos de empleo y otros servicios para latinas ver\u00edan un recorte del 80% bajo el presupuesto propuesto por la gobernadora Mikie Sherrill, un cambio que obligar\u00eda a cerrar tres centros y eliminar servicios para miles de latinas en ocho condados. El [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":32129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false,"token":"eyJpbWciOiJodHRwczpcL1wvd3d3LmFtZXJpY2Fub25ld3NwYXBlci5jb21cL2VzXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wNVwvU2NyZWVuc2hvdC0yMDI2LTA1LTEyLWF0LTkuMTYuMDgtUE0tNzcxeDUwMC5wbmciLCJ0eHQiOiJMb3MgY2VudHJvcyBkZSBzZXJ2aWNpbyBwYXJhIGxhdGluYXMgZW4gTkogZW5mcmVudGFuIGZ1ZXJ0ZXMgcmVjb3J0ZXMgZW4gbGEgYXl1ZGEgZXN0YXRhbCIsInRlbXBsYXRlIjoiaGlnaHdheSIsImZvbnQiOiIiLCJibG9nX2lkIjoyMjg2MTk1NzR9.ULYEJOX4qzDJqmHmTwSGb4DySKvSkOoIboYTJQVjp8kMQ"},"version":2,"media_source":"featured-image","attached_media":[{"id":32129,"url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM.png","type":"image\/jpeg"}]},"_wpas_customize_per_network":false},"categories":[129,246],"tags":[],"class_list":{"0":"post-32126","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-community","8":"category-new-jersey"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Los centros de servicio para latinas en NJ enfrentan fuertes recortes en la ayuda estatal - Americano Newspaper<\/title>\n<meta name=\"description\" content=\"Los centros financiados por el estado que brindan recursos de empleo y otros servicios para latinas ver\u00edan un recorte del 80% bajo el presupuesto propuesto por la gobernadora Mikie Sherrill, un cambio que obligar\u00eda a cerrar tres centros y eliminar servicios para miles de latinas en ocho condados.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los centros de servicio para latinas en NJ enfrentan fuertes recortes en la ayuda estatal\" \/>\n<meta property=\"og:description\" content=\"Los centros financiados por el estado que brindan recursos de empleo y otros servicios para latinas ver\u00edan un recorte del 80% bajo el presupuesto propuesto por la gobernadora Mikie Sherrill, un cambio que obligar\u00eda a cerrar tres centros y eliminar servicios para miles de latinas en ocho condados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/\" \/>\n<meta property=\"og:site_name\" content=\"Americano Newspaper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AmericanoNewspaper\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T01:24:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:24:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-771x500.png\" \/>\n\t<meta property=\"og:image:width\" content=\"771\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Author\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Author\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/\"},\"author\":{\"name\":\"Author\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/person\\\/8967f6b8af7e37bcbbe61f68580ff088\"},\"headline\":\"Los centros de servicio para latinas en NJ enfrentan fuertes recortes en la ayuda estatal\",\"datePublished\":\"2026-05-13T01:24:11+00:00\",\"dateModified\":\"2026-05-13T01:24:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/\"},\"wordCount\":1339,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Screenshot-2026-05-12-at-9.16.08-PM.png\",\"articleSection\":[\"Community\",\"New Jersey\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/\",\"name\":\"Los centros de servicio para latinas en NJ enfrentan fuertes recortes en la ayuda estatal - Americano Newspaper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Screenshot-2026-05-12-at-9.16.08-PM.png\",\"datePublished\":\"2026-05-13T01:24:11+00:00\",\"dateModified\":\"2026-05-13T01:24:18+00:00\",\"description\":\"Los centros financiados por el estado que brindan recursos de empleo y otros servicios para latinas ver\u00edan un recorte del 80% bajo el presupuesto propuesto por la gobernadora Mikie Sherrill, un cambio que obligar\u00eda a cerrar tres centros y eliminar servicios para miles de latinas en ocho condados.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Screenshot-2026-05-12-at-9.16.08-PM.png\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Screenshot-2026-05-12-at-9.16.08-PM.png\",\"width\":1490,\"height\":966,\"caption\":\"La Casa de Don Pedro en Newark forma parte de una red de Hispanic Women's Resource Centers (Centros de Recursos para Mujeres Hispanas) que enfrentan recortes dram\u00e1ticos en la ayuda estatal este a\u00f1o. (Foto de Anne-Marie Caruso\\\/New Jersey Monitor)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/community\\\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los centros de servicio para latinas en NJ enfrentan fuertes recortes en la ayuda estatal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\",\"name\":\"Americano Newspaper\",\"description\":\"The Hispanic Newspaper of New Jersey.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\",\"name\":\"Americano Newspaper\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AmericanoLogoCircle.comCircle2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AmericanoLogoCircle.comCircle2.jpg\",\"width\":600,\"height\":600,\"caption\":\"Americano Newspaper\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AmericanoNewspaper\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/person\\\/8967f6b8af7e37bcbbe61f68580ff088\",\"name\":\"Author\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103\",\"caption\":\"Author\"},\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/author\\\/americano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Los centros de servicio para latinas en NJ enfrentan fuertes recortes en la ayuda estatal - Americano Newspaper","description":"Los centros financiados por el estado que brindan recursos de empleo y otros servicios para latinas ver\u00edan un recorte del 80% bajo el presupuesto propuesto por la gobernadora Mikie Sherrill, un cambio que obligar\u00eda a cerrar tres centros y eliminar servicios para miles de latinas en ocho condados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/","og_locale":"en_US","og_type":"article","og_title":"Los centros de servicio para latinas en NJ enfrentan fuertes recortes en la ayuda estatal","og_description":"Los centros financiados por el estado que brindan recursos de empleo y otros servicios para latinas ver\u00edan un recorte del 80% bajo el presupuesto propuesto por la gobernadora Mikie Sherrill, un cambio que obligar\u00eda a cerrar tres centros y eliminar servicios para miles de latinas en ocho condados.","og_url":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/","og_site_name":"Americano Newspaper","article_publisher":"https:\/\/www.facebook.com\/AmericanoNewspaper\/","article_published_time":"2026-05-13T01:24:11+00:00","article_modified_time":"2026-05-13T01:24:18+00:00","og_image":[{"width":771,"height":500,"url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-771x500.png","type":"image\/png"}],"author":"Author","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Author","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/#article","isPartOf":{"@id":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/"},"author":{"name":"Author","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/person\/8967f6b8af7e37bcbbe61f68580ff088"},"headline":"Los centros de servicio para latinas en NJ enfrentan fuertes recortes en la ayuda estatal","datePublished":"2026-05-13T01:24:11+00:00","dateModified":"2026-05-13T01:24:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/"},"wordCount":1339,"commentCount":0,"publisher":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#organization"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM.png","articleSection":["Community","New Jersey"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/","url":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/","name":"Los centros de servicio para latinas en NJ enfrentan fuertes recortes en la ayuda estatal - Americano Newspaper","isPartOf":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/#primaryimage"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM.png","datePublished":"2026-05-13T01:24:11+00:00","dateModified":"2026-05-13T01:24:18+00:00","description":"Los centros financiados por el estado que brindan recursos de empleo y otros servicios para latinas ver\u00edan un recorte del 80% bajo el presupuesto propuesto por la gobernadora Mikie Sherrill, un cambio que obligar\u00eda a cerrar tres centros y eliminar servicios para miles de latinas en ocho condados.","breadcrumb":{"@id":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/#primaryimage","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM.png","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM.png","width":1490,"height":966,"caption":"La Casa de Don Pedro en Newark forma parte de una red de Hispanic Women's Resource Centers (Centros de Recursos para Mujeres Hispanas) que enfrentan recortes dram\u00e1ticos en la ayuda estatal este a\u00f1o. (Foto de Anne-Marie Caruso\/New Jersey Monitor)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.americanonewspaper.com\/es\/community\/los-centros-de-servicio-para-latinas-en-nj-enfrentan-fuertes-recortes-en-la-ayuda-estatal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.americanonewspaper.com\/es\/"},{"@type":"ListItem","position":2,"name":"Los centros de servicio para latinas en NJ enfrentan fuertes recortes en la ayuda estatal"}]},{"@type":"WebSite","@id":"https:\/\/www.americanonewspaper.com\/es\/#website","url":"https:\/\/www.americanonewspaper.com\/es\/","name":"Americano Newspaper","description":"The Hispanic Newspaper of New Jersey.","publisher":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.americanonewspaper.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.americanonewspaper.com\/es\/#organization","name":"Americano Newspaper","url":"https:\/\/www.americanonewspaper.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2024\/05\/AmericanoLogoCircle.comCircle2.jpg","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2024\/05\/AmericanoLogoCircle.comCircle2.jpg","width":600,"height":600,"caption":"Americano Newspaper"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AmericanoNewspaper\/"]},{"@type":"Person","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/person\/8967f6b8af7e37bcbbe61f68580ff088","name":"Author","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/89ffaf6af3cf6769ffb3c6efb2313947.jpg?ver=1778556103","caption":"Author"},"url":"https:\/\/www.americanonewspaper.com\/es\/author\/americano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM.png","featured_image_urls":{"full":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM.png",1490,966,false],"thumbnail":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-250x250.png",250,250,true],"medium":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-300x194.png",300,194,true],"medium_large":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-768x498.png",696,451,true],"large":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-771x500.png",696,451,true],"1536x1536":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM.png",1490,966,false],"2048x2048":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM.png",1490,966,false],"td_150x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-150x97.png",150,97,true],"td_218x150":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-218x150.png",218,150,true],"td_300x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-300x194.png",300,194,true],"td_324x400":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-324x400.png",324,400,true],"td_485x360":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-485x360.png",485,360,true],"td_696x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-696x451.png",696,451,true],"td_1068x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-1068x692.png",1068,692,true],"td_1920x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM.png",1490,966,false],"bdpp-medium":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2026\/05\/Screenshot-2026-05-12-at-9.16.08-PM-640x480.png",640,480,true]},"author_info":{"display_name":"Author","author_link":"https:\/\/www.americanonewspaper.com\/es\/author\/americano\/"},"category_info":"<a href=\"https:\/\/www.americanonewspaper.com\/es\/category\/community\/\" rel=\"category tag\">Community<\/a> <a href=\"https:\/\/www.americanonewspaper.com\/es\/category\/new-jersey\/\" rel=\"category tag\">New Jersey<\/a>","tag_info":"New Jersey","comment_count":"0","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/32126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/comments?post=32126"}],"version-history":[{"count":1,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/32126\/revisions"}],"predecessor-version":[{"id":32130,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/32126\/revisions\/32130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/media\/32129"}],"wp:attachment":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/media?parent=32126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/categories?post=32126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/tags?post=32126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}