{"id":29201,"date":"2025-10-07T13:27:06","date_gmt":"2025-10-07T17:27:06","guid":{"rendered":"https:\/\/www.americanonewspaper.com\/es\/?p=29201"},"modified":"2025-10-08T10:34:23","modified_gmt":"2025-10-08T14:34:23","slug":"dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos","status":"publish","type":"post","link":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/","title":{"rendered":"&#8216;Dinast\u00eda Casillas&#8217;, un nuevo legado de sangre y poder tras &#8216;El se\u00f1or de los cielos&#8217;"},"content":{"rendered":"\n<p>Los \u00c1ngeles (EE.UU.), (EFE).<\/p>\n\n\n\n<p class=\"dropcapp3\">El universo de uno de los clanes m\u00e1s temidos se expande a partir de este martes con &#8216;Dinast\u00eda Casillas&#8217;, la secuela de &#8216;El se\u00f1or de los cielos&#8217; donde una nueva generaci\u00f3n al mando del imperio criminal que forj\u00f3 Aurelio Casillas se enfrenta a m\u00e1s amenazas, traiciones y el peso de una historia marcada por la sangre.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"365\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-3-800x365.webp\" alt=\"\" class=\"wp-image-29171\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-3-800x365.webp 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-3-300x137.webp 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-3-768x351.webp 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-3-1536x702.webp 1536w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-3-150x69.webp 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-3-696x318.webp 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-3-1068x488.webp 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-3.webp 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Sin el cabeza de familia, el legendario capo interpretado por Rafael Amaya, a su hijo Ismael Casillas (Iv\u00e1n Arana) no le queda otra que tomar las riendas de una estirpe ligada a la tragedia y la lealtad.<\/p>\n\n\n\n<p>&#8220;Es una familia que se ha protegido mucho, que cada uno de los personajes tiene algo que dar. Esa riqueza es lo que puede inspirar&#8221;, afirm\u00f3 el actor mexicano en una entrevista con EFE.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.mikiesherrill.com\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-1-800x445.png\" alt=\"\" class=\"wp-image-29172\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-1-800x445.png 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-1-300x167.png 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-1-768x427.png 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-1-150x83.png 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-1-696x387.png 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-1.png 989w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>Al ya no existir Aurelio Casillas, &#8220;a Ismael no le queda de otra que continuar con el legado y asumir una responsabilidad completamente diferente a la que ya ven\u00eda acostumbrado a tener&#8221;, indica por su parte a EFE Isabella Castillo, quien tambi\u00e9n retoma el personaje de Diana Ahumada para este nuevo proyecto de Telemundo.<\/p>\n\n\n\n<p>Una Diana que volver\u00e1 &#8220;leal y firme para ayudar con todo y echarle ganas&#8221;, agrega Castillo.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.linkedin.com\/in\/jaimeberrios\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"800\" height=\"269\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-4-800x269.jpeg\" alt=\"\" class=\"wp-image-29173\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-4-800x269.jpeg 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-4-300x101.jpeg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-4-768x258.jpeg 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-4-1536x516.jpeg 1536w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-4-150x50.jpeg 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-4-696x234.jpeg 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-4-1068x359.jpeg 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-4.jpeg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>&#8220;Los Casillas se distinguen por ser muy leales y a esta familia le ha pasado de todo. No importa lo que les suceda, siempre van adelante&#8221;, insiste la actriz.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-una-dinastia-actualizada-y-evolucionada\"><strong>Una dinast\u00eda actualizada y evolucionada<\/strong><\/h2>\n\n\n\n<p>A un clan que deber\u00e1 confrontar nuevos retos se suma Ra\u00fal M\u00e9ndez en su papel como &#8216;El Chacorta&#8217;, quien destaca la importancia de actualizarse y adaptarse a los temas de la sociedad actual para seguir conectando con las generaciones m\u00e1s j\u00f3venes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oscartoursdecostarica.com\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"367\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-3-800x367.jpg\" alt=\"\" class=\"wp-image-29174\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-3-800x367.jpg 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-3-300x138.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-3-768x352.jpg 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-3-150x69.jpg 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-3-696x319.jpg 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-3-1068x490.jpg 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-3.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>&#8220;Si la serie como tal ya tiene un tono bien enraizado, hoy en d\u00eda &#8216;Dinast\u00eda Casillas&#8217; tambi\u00e9n empieza a abordar las generaciones que vienen detr\u00e1s de esta primera camada de los Casillas\u201d, indica a EFE.<\/p>\n\n\n\n<p>A diferencia de &#8216;El Se\u00f1or de los cielos&#8217;, &#8220;los personajes con los que se van a encontrar en &#8216;Dinast\u00eda Casillas&#8217; son todav\u00eda m\u00e1s humanos. No existe el universo del bueno y del malo, los personajes se han convertido en seres m\u00e1s humanos&#8221;, explica.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.globalautomall.com\/newdept.cfm\/page\/%20500-savings-for-americano-magazine-readers-2263\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"367\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-1-800x367.webp\" alt=\"\" class=\"wp-image-29175\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-1-800x367.webp 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-1-300x138.webp 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-1-768x352.webp 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-1-150x69.webp 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-1-696x319.webp 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-1-1068x490.webp 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-1.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>&#8220;Al humanizar nuestros personajes, el p\u00fablico se puede identificar m\u00e1s tanto con los nuevos como con los que vienen de atr\u00e1s&#8221;, a\u00f1ade.<\/p>\n\n\n\n<p>Entre esos nuevos rostros destaca Elisabeth Cordero, interpretada por la actriz colombiana Mar\u00eda Fernanda Yepes, un rol que promete ser clave en las nuevas alianzas entre organizaciones.&nbsp;<\/p>\n\n\n\n<p>&#8220;Es un personaje que est\u00e1 todo el tiempo reclamando su voz\u2026 hoy en d\u00eda est\u00e1 recuperando su voz y yo eso lo veo muy bonito, porque creo que es un gran mensaje para las mujeres&#8221;, afirma Yepes a EFE.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.njng.com\/my-account\/payment-options\/payment-assistance.aspx\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"336\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-800x336.png\" alt=\"\" class=\"wp-image-29087\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-800x336.png 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-300x126.png 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-768x322.png 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-1536x645.png 1536w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-150x63.png 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-696x292.png 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-1068x448.png 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1.png 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>Adem\u00e1s de fungir de puente entre dos grandes clanes, los Casillas y los Chemas, &#8220;es una mujer que est\u00e1 tambi\u00e9n mostr\u00e1ndose capaz de manejar una empresa, una organizaci\u00f3n, tomar decisiones. Me parece lindo que tambi\u00e9n este personaje est\u00e9 trayendo eso a estas nuevas generaciones&#8221;, dice.&nbsp;<\/p>\n\n\n\n<p>Aunque el linaje de los Casillas extiende su historia en la televisi\u00f3n, su popularidad se sostiene sobre personajes que el p\u00fablico ya conoce en la peque\u00f1a pantalla que durante han servido como el pilar central de la saga.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.peapackprivate.com\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"433\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-1-800x433.png\" alt=\"\" class=\"wp-image-29052\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-1-800x433.png 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-1-300x162.png 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-1-768x416.png 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-1-1536x832.png 1536w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-1-150x81.png 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-1-696x377.png 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-1-1068x578.png 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-1.png 1596w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>&#8220;Nos han acompa\u00f1ado tantos a\u00f1os y ya son personajes que no tienen que creerse, sino que ya conocen. Entonces, ahora es verlos en una nueva situaci\u00f3n y ver c\u00f3mo se comportan, c\u00f3mo salen de esas\u2026 creo que eso ser\u00e1 divertido&#8221;, asegura Aranda.<\/p>\n\n\n\n<p>Es por ello que la audiencia &#8220;se va a poner contenta, se va a divertir much\u00edsimo y se va a alegrar mucho. Les va a dar gusto ver c\u00f3mo los Casillas, a pesar de todo, siguen firmes&#8221;, sentencia por su parte Castillo.&nbsp;<\/p>\n\n\n\n<p>Mikaela Viqueira<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.shu.edu\/latino-institute\/annual-gala.html\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"367\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-800x367.webp\" alt=\"\" class=\"wp-image-28950\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-800x367.webp 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-300x138.webp 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-768x352.webp 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-150x69.webp 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-696x319.webp 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-1068x490.webp 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/tayakan.com\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"236\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-800x236.jpeg\" alt=\"\" class=\"wp-image-29142\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-800x236.jpeg 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-300x89.jpeg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-768x227.jpeg 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-1536x453.jpeg 1536w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-150x44.jpeg 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-696x205.jpeg 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-1068x315.jpeg 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2.jpeg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Los \u00c1ngeles (EE.UU.), (EFE). El universo de uno de los clanes m\u00e1s temidos se expande a partir de este martes con &#8216;Dinast\u00eda Casillas&#8217;, la secuela de &#8216;El se\u00f1or de los cielos&#8217; donde una nueva generaci\u00f3n al mando del imperio criminal que forj\u00f3 Aurelio Casillas se enfrenta a m\u00e1s amenazas, traiciones y el peso de una [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":29202,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[1321,1322,738],"tags":[],"class_list":{"0":"post-29201","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-el-senor-de-los-cielos","8":"category-los-angeles-2","9":"category-series"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&#039;Dinast\u00eda Casillas&#039;, un nuevo legado de sangre y poder tras &#039;El se\u00f1or de los cielos&#039; - Americano Newspaper<\/title>\n<meta name=\"description\" content=\"El universo de uno de los clanes m\u00e1s temidos se expande a partir de este martes con &#039;Dinast\u00eda Casillas&#039;, la secuela de &#039;El se\u00f1or de los cielos&#039; donde una nueva generaci\u00f3n al mando del imperio criminal que forj\u00f3 Aurelio Casillas se enfrenta a m\u00e1s amenazas, traiciones y el peso de una historia marcada por la sangre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;Dinast\u00eda Casillas&#039;, un nuevo legado de sangre y poder tras &#039;El se\u00f1or de los cielos&#039;\" \/>\n<meta property=\"og:description\" content=\"El universo de uno de los clanes m\u00e1s temidos se expande a partir de este martes con &#039;Dinast\u00eda Casillas&#039;, la secuela de &#039;El se\u00f1or de los cielos&#039; donde una nueva generaci\u00f3n al mando del imperio criminal que forj\u00f3 Aurelio Casillas se enfrenta a m\u00e1s amenazas, traiciones y el peso de una historia marcada por la sangre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/\" \/>\n<meta property=\"og:site_name\" content=\"Americano Newspaper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AmericanoNewspaper\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-07T17:27:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T14:34:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Harmony Quintana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Harmony Quintana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/\"},\"author\":{\"name\":\"Harmony Quintana\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/person\\\/82c7c1ac5e9a005b627b6c7db5361c90\"},\"headline\":\"&#8216;Dinast\u00eda Casillas&#8217;, un nuevo legado de sangre y poder tras &#8216;El se\u00f1or de los cielos&#8217;\",\"datePublished\":\"2025-10-07T17:27:06+00:00\",\"dateModified\":\"2025-10-08T14:34:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/\"},\"wordCount\":677,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg\",\"articleSection\":[\"El se\u00f1or de los cielos\",\"Los \u00c1ngeles\",\"Series\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/\",\"name\":\"'Dinast\u00eda Casillas', un nuevo legado de sangre y poder tras 'El se\u00f1or de los cielos' - Americano Newspaper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg\",\"datePublished\":\"2025-10-07T17:27:06+00:00\",\"dateModified\":\"2025-10-08T14:34:23+00:00\",\"description\":\"El universo de uno de los clanes m\u00e1s temidos se expande a partir de este martes con 'Dinast\u00eda Casillas', la secuela de 'El se\u00f1or de los cielos' donde una nueva generaci\u00f3n al mando del imperio criminal que forj\u00f3 Aurelio Casillas se enfrenta a m\u00e1s amenazas, traiciones y el peso de una historia marcada por la sangre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg\",\"width\":900,\"height\":600,\"caption\":\"De izquierda a derecha: Silvana Effio, Iv\u00e1n Arana, Mar\u00eda Fernanda Yepes, Isabella Castillo y Ra\u00fal M\u00e9ndez posan durante la premier de 'Dinastia Casillas', en Los \u00c1ngeles (EE.UU.). EFE\\\/ Telemundo Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/el-senor-de-los-cielos\\\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;Dinast\u00eda Casillas&#8217;, un nuevo legado de sangre y poder tras &#8216;El se\u00f1or de los cielos&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\",\"name\":\"Americano Newspaper\",\"description\":\"The Hispanic Newspaper of New Jersey.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\",\"name\":\"Americano Newspaper\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AmericanoLogoCircle.comCircle2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AmericanoLogoCircle.comCircle2.jpg\",\"width\":600,\"height\":600,\"caption\":\"Americano Newspaper\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AmericanoNewspaper\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/person\\\/82c7c1ac5e9a005b627b6c7db5361c90\",\"name\":\"Harmony Quintana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637\",\"caption\":\"Harmony Quintana\"},\"sameAs\":[\"http:\\\/\\\/www.americanonewspaper.com\"],\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/author\\\/harmony\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"'Dinast\u00eda Casillas', un nuevo legado de sangre y poder tras 'El se\u00f1or de los cielos' - Americano Newspaper","description":"El universo de uno de los clanes m\u00e1s temidos se expande a partir de este martes con 'Dinast\u00eda Casillas', la secuela de 'El se\u00f1or de los cielos' donde una nueva generaci\u00f3n al mando del imperio criminal que forj\u00f3 Aurelio Casillas se enfrenta a m\u00e1s amenazas, traiciones y el peso de una historia marcada por la sangre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/","og_locale":"en_US","og_type":"article","og_title":"'Dinast\u00eda Casillas', un nuevo legado de sangre y poder tras 'El se\u00f1or de los cielos'","og_description":"El universo de uno de los clanes m\u00e1s temidos se expande a partir de este martes con 'Dinast\u00eda Casillas', la secuela de 'El se\u00f1or de los cielos' donde una nueva generaci\u00f3n al mando del imperio criminal que forj\u00f3 Aurelio Casillas se enfrenta a m\u00e1s amenazas, traiciones y el peso de una historia marcada por la sangre.","og_url":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/","og_site_name":"Americano Newspaper","article_publisher":"https:\/\/www.facebook.com\/AmericanoNewspaper\/","article_published_time":"2025-10-07T17:27:06+00:00","article_modified_time":"2025-10-08T14:34:23+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg","type":"image\/jpeg"}],"author":"Harmony Quintana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Harmony Quintana","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/#article","isPartOf":{"@id":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/"},"author":{"name":"Harmony Quintana","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/person\/82c7c1ac5e9a005b627b6c7db5361c90"},"headline":"&#8216;Dinast\u00eda Casillas&#8217;, un nuevo legado de sangre y poder tras &#8216;El se\u00f1or de los cielos&#8217;","datePublished":"2025-10-07T17:27:06+00:00","dateModified":"2025-10-08T14:34:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/"},"wordCount":677,"commentCount":0,"publisher":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#organization"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg","articleSection":["El se\u00f1or de los cielos","Los \u00c1ngeles","Series"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/","url":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/","name":"'Dinast\u00eda Casillas', un nuevo legado de sangre y poder tras 'El se\u00f1or de los cielos' - Americano Newspaper","isPartOf":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/#primaryimage"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg","datePublished":"2025-10-07T17:27:06+00:00","dateModified":"2025-10-08T14:34:23+00:00","description":"El universo de uno de los clanes m\u00e1s temidos se expande a partir de este martes con 'Dinast\u00eda Casillas', la secuela de 'El se\u00f1or de los cielos' donde una nueva generaci\u00f3n al mando del imperio criminal que forj\u00f3 Aurelio Casillas se enfrenta a m\u00e1s amenazas, traiciones y el peso de una historia marcada por la sangre.","breadcrumb":{"@id":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/#primaryimage","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg","width":900,"height":600,"caption":"De izquierda a derecha: Silvana Effio, Iv\u00e1n Arana, Mar\u00eda Fernanda Yepes, Isabella Castillo y Ra\u00fal M\u00e9ndez posan durante la premier de 'Dinastia Casillas', en Los \u00c1ngeles (EE.UU.). EFE\/ Telemundo Media"},{"@type":"BreadcrumbList","@id":"https:\/\/www.americanonewspaper.com\/es\/el-senor-de-los-cielos\/dinastia-casillas-un-nuevo-legado-de-sangre-y-poder-tras-el-senor-de-los-cielos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.americanonewspaper.com\/es\/"},{"@type":"ListItem","position":2,"name":"&#8216;Dinast\u00eda Casillas&#8217;, un nuevo legado de sangre y poder tras &#8216;El se\u00f1or de los cielos&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.americanonewspaper.com\/es\/#website","url":"https:\/\/www.americanonewspaper.com\/es\/","name":"Americano Newspaper","description":"The Hispanic Newspaper of New Jersey.","publisher":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.americanonewspaper.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.americanonewspaper.com\/es\/#organization","name":"Americano Newspaper","url":"https:\/\/www.americanonewspaper.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2024\/05\/AmericanoLogoCircle.comCircle2.jpg","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2024\/05\/AmericanoLogoCircle.comCircle2.jpg","width":600,"height":600,"caption":"Americano Newspaper"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AmericanoNewspaper\/"]},{"@type":"Person","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/person\/82c7c1ac5e9a005b627b6c7db5361c90","name":"Harmony Quintana","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637","caption":"Harmony Quintana"},"sameAs":["http:\/\/www.americanonewspaper.com"],"url":"https:\/\/www.americanonewspaper.com\/es\/author\/harmony\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg","featured_image_urls":{"full":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg",900,600,false],"thumbnail":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw-250x250.jpg",250,250,true],"medium":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw-768x512.jpg",696,464,true],"large":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw-750x500.jpg",696,464,true],"1536x1536":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg",900,600,false],"2048x2048":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg",900,600,false],"td_150x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw-150x100.jpg",150,100,true],"td_218x150":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw-218x150.jpg",218,150,true],"td_300x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw-300x200.jpg",300,200,true],"td_324x400":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw-324x400.jpg",324,400,true],"td_485x360":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw-485x360.jpg",485,360,true],"td_696x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw-696x464.jpg",696,464,true],"td_1068x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg",900,600,false],"td_1920x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw.jpg",900,600,false],"bdpp-medium":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/b4e4683d832e8683ba4531bba7700a446064a305miniw-640x480.jpg",640,480,true]},"author_info":{"display_name":"Harmony Quintana","author_link":"https:\/\/www.americanonewspaper.com\/es\/author\/harmony\/"},"category_info":"<a href=\"https:\/\/www.americanonewspaper.com\/es\/category\/el-senor-de-los-cielos\/\" rel=\"category tag\">El se\u00f1or de los cielos<\/a> <a href=\"https:\/\/www.americanonewspaper.com\/es\/category\/los-angeles-2\/\" rel=\"category tag\">Los \u00c1ngeles<\/a> <a href=\"https:\/\/www.americanonewspaper.com\/es\/category\/series\/\" rel=\"category tag\">Series<\/a>","tag_info":"Series","comment_count":"0","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/29201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/comments?post=29201"}],"version-history":[{"count":2,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/29201\/revisions"}],"predecessor-version":[{"id":29225,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/29201\/revisions\/29225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/media\/29202"}],"wp:attachment":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/media?parent=29201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/categories?post=29201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/tags?post=29201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}