{"id":29165,"date":"2025-10-06T09:40:49","date_gmt":"2025-10-06T13:40:49","guid":{"rendered":"https:\/\/www.americanonewspaper.com\/es\/?p=29165"},"modified":"2025-10-06T11:37:35","modified_gmt":"2025-10-06T15:37:35","slug":"empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica","status":"publish","type":"post","link":"https:\/\/www.americanonewspaper.com\/es\/criptomonedas\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/","title":{"rendered":"Empresas en Florida adoptan las criptomonedas para exportar mercanc\u00edas a Latinoam\u00e9rica"},"content":{"rendered":"\n<p>Miami (EE.UU.), (EFE).<\/p>\n\n\n\n<p class=\"dropcapp3\">Empresas en Florida est\u00e1n adoptando el uso de criptomonedas para exportar productos a pa\u00edses de Latinoam\u00e9rica con divisas inestables, como Argentina y Venezuela, una tendencia que emprendedores atribuyen, en parte, a nuevas pol\u00edticas del Gobierno de Estados Unidos favorables para estos activos digitales.<\/p>\n\n\n\n<p>El empresario italovenezolano Giovanni Giannone not\u00f3 un cambio en sus ventas cuando comenz\u00f3 a aceptar pagos con criptomonedas estables de sus clientes en Argentina, Colombia, Ecuador, Honduras, Nicaragua y Rep\u00fablica Dominicana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"365\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-2-800x365.webp\" alt=\"\" class=\"wp-image-29136\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-2-800x365.webp 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-2-300x137.webp 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-2-768x351.webp 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-2-1536x702.webp 1536w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-2-150x69.webp 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-2-696x318.webp 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-2-1068x488.webp 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-02-20-at-9.11.40-AM-1920x877-2-2.webp 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>A estos pa\u00edses distribuye tecnolog\u00eda al por mayor a trav\u00e9s de Jireh Tech Solutions, la empresa que fund\u00f3 en 2023 y que se dedica a la compra y comercializaci\u00f3n de equipos reacondicionados.<\/p>\n\n\n\n<p>&#8220;Para ellos es un beneficio porque el tema con clientes de Latinoam\u00e9rica es que muchas veces adquieren estos activos por un tema de resguardar tambi\u00e9n su patrimonio, o sea, en pa\u00edses en los que tal vez el control cambiario es muy variante&#8221;, manifiesta el emprendedor en una entrevista con EFE en Miami.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.mikiesherrill.com\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-800x445.png\" alt=\"\" class=\"wp-image-29140\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-800x445.png 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-300x167.png 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-768x427.png 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-150x83.png 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3-696x387.png 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-09-24-at-11.48.15-AM-1-3.png 989w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>Giannone, cuya firma compra lotes de iPhone usados, certifica su funcionamiento y los distribuye a revendedores en Am\u00e9rica Latina, se acerc\u00f3 a la plataforma Shield, cofundada por un emprendedor latino para ayudar a compa\u00f1\u00edas a hacer transacciones en criptomonedas estables, como la USDT, vinculada al valor del d\u00f3lar estadounidense.<\/p>\n\n\n\n<p>De esta manera, detalla el comerciante, los clientes extranjeros pueden pagarle a Jireh Tech Solutions en criptomonedas respaldadas por la divisa estadounidense y evitar una depreciaci\u00f3n cambiaria con la certeza de que cumplen las nuevas regulaciones que exige Estados Unidos, pero con menor burocracia bancaria.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.linkedin.com\/in\/jaimeberrios\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"800\" height=\"269\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-3-800x269.jpeg\" alt=\"\" class=\"wp-image-29138\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-3-800x269.jpeg 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-3-300x101.jpeg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-3-768x258.jpeg 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-3-1536x516.jpeg 1536w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-3-150x50.jpeg 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-3-696x234.jpeg 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-3-1068x359.jpeg 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-02-at-3.35.45-PM-3.jpeg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>&#8220;Es una soluci\u00f3n que nos ayuda a poder crecer en los clientes que recibimos, a poder ofrecerles una segunda opci\u00f3n a ellos porque normalmente lo que nosotros hac\u00edamos era recibir solamente &#8216;wire transfers&#8217; (transferencias bancarias) con todos los clientes y no hab\u00eda una segunda opci\u00f3n para todos ellos&#8221;, se\u00f1ala.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-el-auge-de-las-criptomonedas-en-eeuu\"><strong>El auge de las criptomonedas en EEUU<\/strong><\/h2>\n\n\n\n<p>El fen\u00f3meno ocurre en medio del impulso de la Administraci\u00f3n de Donald Trump, quien en julio firm\u00f3 la Ley GENIUS, la primera que establece un r\u00e9gimen regulatorio para las criptomonedas que est\u00e1n respaldadas por activos considerados confiables, como el d\u00f3lar, lo que contrasta con las especulativas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oscartoursdecostarica.com\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"367\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-2-800x367.jpg\" alt=\"\" class=\"wp-image-29137\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-2-800x367.jpg 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-2-300x138.jpg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-2-768x352.jpg 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-2-150x69.jpg 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-2-696x319.jpg 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-2-1068x490.jpg 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/OscarCalvo-copy-1-2.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>En este contexto, ha crecido un 22 % el valor del mercado global de las criptomonedas estables, hasta los 250.000 millones de d\u00f3lares, mientras que hay transacciones diarias por 100.000 millones de d\u00f3lares en esta divisa virtual, seg\u00fan un reporte de Morgan Stanley.<\/p>\n\n\n\n<p>Esto anima a Luis Carchi, cofundador de Shield, plataforma que facilita a las empresas hacer estas transacciones y quien asegura que esto apenas es el &#8220;inicio de esta revoluci\u00f3n&#8221; en una entrevista con EFE desde sus oficinas en Miami.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.globalautomall.com\/newdept.cfm\/page\/%20500-savings-for-americano-magazine-readers-2263\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"367\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-800x367.webp\" alt=\"\" class=\"wp-image-29141\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-800x367.webp 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-300x138.webp 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-768x352.webp 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-150x69.webp 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-696x319.webp 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf-1068x490.webp 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Globalhalf.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>&#8220;Antes la Presidencia de EE.UU. no apoyaba, sino al contrario, atacaba a las empresas que trabajaban con activos digitales, y estaba demandando a la mayor\u00eda de las empresas grandes de EE.UU. Hoy en d\u00eda ha cambiado totalmente esa pol\u00edtica de ese punto de vista, que creo que es lo m\u00e1s importante en temas de regulaciones&#8221;, dice.<\/p>\n\n\n\n<p>Desde su lanzamiento en 2022, Shield ha procesado m\u00e1s de 100 millones de d\u00f3lares en pagos, de los que 40 millones ocurrieron solo en el \u00faltimo mes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.njng.com\/my-account\/payment-options\/payment-assistance.aspx\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"336\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-800x336.png\" alt=\"\" class=\"wp-image-29087\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-800x336.png 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-300x126.png 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-768x322.png 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-1536x645.png 1536w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-150x63.png 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-696x292.png 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1-1068x448.png 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-10-01-at-7.31.56-PM-1920x806-1.png 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-perder-el-miedo\"><strong>Perder el miedo<\/strong><\/h2>\n\n\n\n<p>Carchi pide a los emprendedores perder el miedo, pues &#8220;nunca ha sido ilegal en Estados Unidos comprar o vender una criptomoneda&#8221;, adem\u00e1s de enfatizar que existen versiones estables como la USDT.<\/p>\n\n\n\n<p>&#8220;Usualmente, cuando uno menciona cripto tiene un mal sabor para mucha gente, pensamos en estafas, en especulaci\u00f3n y trampas que se esconden como inversi\u00f3n. El USDT no tiene nada que ver con invertir en activos digitales, es simplemente, como yo le llamo, un criptod\u00f3lar, un d\u00f3lar digital&#8221;, describe.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.peapackprivate.com\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"433\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-2-800x433.png\" alt=\"\" class=\"wp-image-29093\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-2-800x433.png 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-2-300x162.png 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-2-768x416.png 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-2-1536x832.png 1536w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-2-150x81.png 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-2-696x377.png 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-2-1068x578.png 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/Screenshot-2025-08-15-at-4.21.12-PM-1-2.png 1596w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>Giannone reconoce su escepticismo inicial, pero ahora dice a empresarios como \u00e9l que, &#8220;cuando tienen recelo, es el desconocimiento&#8221;.<\/p>\n\n\n\n<p>&#8220;Normalmente, muchas de las compa\u00f1\u00edas que no adoptan este tipo de soluciones lo hacen desde una visi\u00f3n del pasado, de tal vez no adoptar nuevas herramientas, como la empresa que todav\u00eda en nuestro rubro sigue enviando listas de precios en Excel&#8221;, concluye.<\/p>\n\n\n\n<p>Pedro Pablo Cort\u00e9s<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.shu.edu\/latino-institute\/annual-gala.html\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"367\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-800x367.webp\" alt=\"\" class=\"wp-image-28950\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-800x367.webp 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-300x138.webp 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-768x352.webp 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-150x69.webp 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-696x319.webp 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2-1068x490.webp 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/09\/Maria-Seton-Hall-4-1-2.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/tayakan.com\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"236\" src=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-800x236.jpeg\" alt=\"\" class=\"wp-image-29142\" srcset=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-800x236.jpeg 800w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-300x89.jpeg 300w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-768x227.jpeg 768w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-1536x453.jpeg 1536w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-150x44.jpeg 150w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-696x205.jpeg 696w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2-1068x315.jpeg 1068w, https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-09-at-8.17.12-PM-2.jpeg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Miami (EE.UU.), (EFE). Empresas en Florida est\u00e1n adoptando el uso de criptomonedas para exportar productos a pa\u00edses de Latinoam\u00e9rica con divisas inestables, como Argentina y Venezuela, una tendencia que emprendedores atribuyen, en parte, a nuevas pol\u00edticas del Gobierno de Estados Unidos favorables para estos activos digitales. El empresario italovenezolano Giovanni Giannone not\u00f3 un cambio en [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":29166,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[1317,227],"tags":[],"class_list":{"0":"post-29165","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-criptomonedas","8":"category-miami"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Empresas en Florida adoptan las criptomonedas para exportar mercanc\u00edas a Latinoam\u00e9rica - Americano Newspaper<\/title>\n<meta name=\"description\" content=\"Empresas en Florida est\u00e1n adoptando el uso de criptomonedas para exportar productos a pa\u00edses de Latinoam\u00e9rica con divisas inestables, como Argentina y Venezuela, una tendencia que emprendedores atribuyen, en parte, a nuevas pol\u00edticas del Gobierno de Estados Unidos favorables para estos activos digitales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empresas en Florida adoptan las criptomonedas para exportar mercanc\u00edas a Latinoam\u00e9rica\" \/>\n<meta property=\"og:description\" content=\"Empresas en Florida est\u00e1n adoptando el uso de criptomonedas para exportar productos a pa\u00edses de Latinoam\u00e9rica con divisas inestables, como Argentina y Venezuela, una tendencia que emprendedores atribuyen, en parte, a nuevas pol\u00edticas del Gobierno de Estados Unidos favorables para estos activos digitales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/\" \/>\n<meta property=\"og:site_name\" content=\"Americano Newspaper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AmericanoNewspaper\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-06T13:40:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-06T15:37:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Harmony Quintana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Harmony Quintana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/\"},\"author\":{\"name\":\"Harmony Quintana\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/person\\\/82c7c1ac5e9a005b627b6c7db5361c90\"},\"headline\":\"Empresas en Florida adoptan las criptomonedas para exportar mercanc\u00edas a Latinoam\u00e9rica\",\"datePublished\":\"2025-10-06T13:40:49+00:00\",\"dateModified\":\"2025-10-06T15:37:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/\"},\"wordCount\":723,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg\",\"articleSection\":[\"Criptomonedas\",\"Miami\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/\",\"name\":\"Empresas en Florida adoptan las criptomonedas para exportar mercanc\u00edas a Latinoam\u00e9rica - Americano Newspaper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg\",\"datePublished\":\"2025-10-06T13:40:49+00:00\",\"dateModified\":\"2025-10-06T15:37:35+00:00\",\"description\":\"Empresas en Florida est\u00e1n adoptando el uso de criptomonedas para exportar productos a pa\u00edses de Latinoam\u00e9rica con divisas inestables, como Argentina y Venezuela, una tendencia que emprendedores atribuyen, en parte, a nuevas pol\u00edticas del Gobierno de Estados Unidos favorables para estos activos digitales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg\",\"width\":900,\"height\":675,\"caption\":\"El cofundador de Shield Luis Carchi habla durante una entrevista con EFE este lunes, en Miami (Estados Unidos). EFE\\\/ Alberto Boal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/miami\\\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresas en Florida adoptan las criptomonedas para exportar mercanc\u00edas a Latinoam\u00e9rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\",\"name\":\"Americano Newspaper\",\"description\":\"The Hispanic Newspaper of New Jersey.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#organization\",\"name\":\"Americano Newspaper\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AmericanoLogoCircle.comCircle2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AmericanoLogoCircle.comCircle2.jpg\",\"width\":600,\"height\":600,\"caption\":\"Americano Newspaper\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AmericanoNewspaper\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/#\\\/schema\\\/person\\\/82c7c1ac5e9a005b627b6c7db5361c90\",\"name\":\"Harmony Quintana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637\",\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637\",\"contentUrl\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637\",\"caption\":\"Harmony Quintana\"},\"sameAs\":[\"http:\\\/\\\/www.americanonewspaper.com\"],\"url\":\"https:\\\/\\\/www.americanonewspaper.com\\\/es\\\/author\\\/harmony\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Empresas en Florida adoptan las criptomonedas para exportar mercanc\u00edas a Latinoam\u00e9rica - Americano Newspaper","description":"Empresas en Florida est\u00e1n adoptando el uso de criptomonedas para exportar productos a pa\u00edses de Latinoam\u00e9rica con divisas inestables, como Argentina y Venezuela, una tendencia que emprendedores atribuyen, en parte, a nuevas pol\u00edticas del Gobierno de Estados Unidos favorables para estos activos digitales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/","og_locale":"en_US","og_type":"article","og_title":"Empresas en Florida adoptan las criptomonedas para exportar mercanc\u00edas a Latinoam\u00e9rica","og_description":"Empresas en Florida est\u00e1n adoptando el uso de criptomonedas para exportar productos a pa\u00edses de Latinoam\u00e9rica con divisas inestables, como Argentina y Venezuela, una tendencia que emprendedores atribuyen, en parte, a nuevas pol\u00edticas del Gobierno de Estados Unidos favorables para estos activos digitales.","og_url":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/","og_site_name":"Americano Newspaper","article_publisher":"https:\/\/www.facebook.com\/AmericanoNewspaper\/","article_published_time":"2025-10-06T13:40:49+00:00","article_modified_time":"2025-10-06T15:37:35+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg","type":"image\/jpeg"}],"author":"Harmony Quintana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Harmony Quintana","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/#article","isPartOf":{"@id":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/"},"author":{"name":"Harmony Quintana","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/person\/82c7c1ac5e9a005b627b6c7db5361c90"},"headline":"Empresas en Florida adoptan las criptomonedas para exportar mercanc\u00edas a Latinoam\u00e9rica","datePublished":"2025-10-06T13:40:49+00:00","dateModified":"2025-10-06T15:37:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/"},"wordCount":723,"commentCount":0,"publisher":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#organization"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg","articleSection":["Criptomonedas","Miami"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/","url":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/","name":"Empresas en Florida adoptan las criptomonedas para exportar mercanc\u00edas a Latinoam\u00e9rica - Americano Newspaper","isPartOf":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/#primaryimage"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg","datePublished":"2025-10-06T13:40:49+00:00","dateModified":"2025-10-06T15:37:35+00:00","description":"Empresas en Florida est\u00e1n adoptando el uso de criptomonedas para exportar productos a pa\u00edses de Latinoam\u00e9rica con divisas inestables, como Argentina y Venezuela, una tendencia que emprendedores atribuyen, en parte, a nuevas pol\u00edticas del Gobierno de Estados Unidos favorables para estos activos digitales.","breadcrumb":{"@id":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/#primaryimage","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg","width":900,"height":675,"caption":"El cofundador de Shield Luis Carchi habla durante una entrevista con EFE este lunes, en Miami (Estados Unidos). EFE\/ Alberto Boal"},{"@type":"BreadcrumbList","@id":"https:\/\/www.americanonewspaper.com\/es\/miami\/empresas-en-florida-adoptan-las-criptomonedas-para-exportar-mercancias-a-latinoamerica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.americanonewspaper.com\/es\/"},{"@type":"ListItem","position":2,"name":"Empresas en Florida adoptan las criptomonedas para exportar mercanc\u00edas a Latinoam\u00e9rica"}]},{"@type":"WebSite","@id":"https:\/\/www.americanonewspaper.com\/es\/#website","url":"https:\/\/www.americanonewspaper.com\/es\/","name":"Americano Newspaper","description":"The Hispanic Newspaper of New Jersey.","publisher":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.americanonewspaper.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.americanonewspaper.com\/es\/#organization","name":"Americano Newspaper","url":"https:\/\/www.americanonewspaper.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2024\/05\/AmericanoLogoCircle.comCircle2.jpg","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2024\/05\/AmericanoLogoCircle.comCircle2.jpg","width":600,"height":600,"caption":"Americano Newspaper"},"image":{"@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AmericanoNewspaper\/"]},{"@type":"Person","@id":"https:\/\/www.americanonewspaper.com\/es\/#\/schema\/person\/82c7c1ac5e9a005b627b6c7db5361c90","name":"Harmony Quintana","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637","url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637","contentUrl":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/litespeed\/avatar\/656e5d40e40a67e90b0fee2acae8a764.jpg?ver=1778556637","caption":"Harmony Quintana"},"sameAs":["http:\/\/www.americanonewspaper.com"],"url":"https:\/\/www.americanonewspaper.com\/es\/author\/harmony\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg","featured_image_urls":{"full":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg",900,675,false],"thumbnail":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw-250x250.jpg",250,250,true],"medium":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw-300x225.jpg",300,225,true],"medium_large":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw-768x576.jpg",696,522,true],"large":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw-667x500.jpg",667,500,true],"1536x1536":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg",900,675,false],"2048x2048":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg",900,675,false],"td_150x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw-150x113.jpg",150,113,true],"td_218x150":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw-218x150.jpg",218,150,true],"td_300x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw-300x225.jpg",300,225,true],"td_324x400":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw-324x400.jpg",324,400,true],"td_485x360":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw-485x360.jpg",485,360,true],"td_696x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw-696x522.jpg",696,522,true],"td_1068x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg",900,675,false],"td_1920x0":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw.jpg",900,675,false],"bdpp-medium":["https:\/\/www.americanonewspaper.com\/es\/wp-content\/uploads\/2025\/10\/6bf6bf59970a4b6b9604b22bd9100fa19d2f369aminiw-640x480.jpg",640,480,true]},"author_info":{"display_name":"Harmony Quintana","author_link":"https:\/\/www.americanonewspaper.com\/es\/author\/harmony\/"},"category_info":"<a href=\"https:\/\/www.americanonewspaper.com\/es\/category\/criptomonedas\/\" rel=\"category tag\">Criptomonedas<\/a> <a href=\"https:\/\/www.americanonewspaper.com\/es\/category\/miami\/\" rel=\"category tag\">Miami<\/a>","tag_info":"Miami","comment_count":"0","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/29165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/comments?post=29165"}],"version-history":[{"count":1,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/29165\/revisions"}],"predecessor-version":[{"id":29167,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/posts\/29165\/revisions\/29167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/media\/29166"}],"wp:attachment":[{"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/media?parent=29165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/categories?post=29165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.americanonewspaper.com\/es\/wp-json\/wp\/v2\/tags?post=29165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}